{"id":468,"date":"2024-12-31T00:51:14","date_gmt":"2024-12-30T23:51:14","guid":{"rendered":"https:\/\/drromanovaleria.ch\/?page_id=468"},"modified":"2026-06-25T14:40:45","modified_gmt":"2026-06-25T12:40:45","slug":"alopecia","status":"publish","type":"page","link":"https:\/\/drromanovaleria.ch\/en\/besoins\/peau-et-cheveux\/alopecie\/","title":{"rendered":"Alopecia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"468\" class=\"elementor elementor-468\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5079470 e-flex e-con-boxed e-con e-parent\" data-id=\"5079470\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d097e0d e-con-full e-flex e-con e-child\" data-id=\"d097e0d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b763ac6 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b763ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CHUTE DE CHEVEUX : SOINS M\u00c9DICAUX CAPILLAIRES\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85f2c0d elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"85f2c0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/drromanovaleria.ch\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee23c3c e-flex e-con-boxed e-con e-parent\" data-id=\"ee23c3c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e1e97f6 e-flex e-con-boxed e-con e-child\" data-id=\"e1e97f6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d7c772 e-con-full e-flex e-con e-child\" data-id=\"9d7c772\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc25976 elementor-widget elementor-widget-heading\" data-id=\"cc25976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu\u2019est-ce que c\u2019est la chute de cheveux ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02b9a67 elementor-widget elementor-widget-text-editor\" data-id=\"02b9a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"72\" data-end=\"416\">Les cheveux sont un symbole de s\u00e9duction, de sant\u00e9 et de vitalit\u00e9. Chaque individu poss\u00e8de en moyenne entre 80 000 et 160 000 cheveux, qui se renouvellent naturellement sur un cycle de 3 \u00e0 5 ans. Il est normal d\u2019en perdre 50 \u00e0 100 par jour. Lorsque cette chute s\u2019accentue et que la repousse ne compense plus la perte, on parle alors d\u2019alop\u00e9cie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8b4831 e-flex e-con-boxed e-con e-child\" data-id=\"f8b4831\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bee1aff elementor-widget elementor-widget-image\" data-id=\"bee1aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"280\" height=\"245\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp\" class=\"attachment-medium size-medium wp-image-4847\" alt=\"photo cheveux forts\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp 280w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux-14x12.webp 14w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a0da0f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a0da0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/drromanovaleria.ch\/contactez-le-dr-romano\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prendre rendez-vous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3013c6d e-flex e-con-boxed e-con e-parent\" data-id=\"3013c6d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c54440 elementor-toc--content-ellipsis elementor-toc--minimized-on-desktop elementor-widget elementor-widget-table-of-contents\" data-id=\"2c54440\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;minimized_on&quot;:&quot;desktop&quot;,&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tSommaire\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__2c54440\" aria-expanded=\"true\" aria-label=\"Ouvrir la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__2c54440\" aria-expanded=\"true\" aria-label=\"Fermer la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__2c54440\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42efeb2 e-flex e-con-boxed e-con e-parent\" data-id=\"42efeb2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11d72b5 elementor-widget elementor-widget-heading\" data-id=\"11d72b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Points forts<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74d3ee4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"74d3ee4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fba44b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3fba44b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79430cd elementor-widget elementor-widget-text-editor\" data-id=\"79430cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Traitement de la chute de cheveux \u00e0 Gen\u00e8ve<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df88632 e-flex e-con-boxed e-con e-child\" data-id=\"df88632\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eac6a81 e-flex e-con-boxed e-con e-child\" data-id=\"eac6a81\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd6dff1 elementor-widget elementor-widget-text-editor\" data-id=\"bd6dff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;alop\u00e9cie, qu&#8217;elle affecte les femmes ou les hommes, est un probl\u00e8me capillaire fr\u00e9quent qui a souvent un impact sur la qualit\u00e9 de vie. <br \/>La forme la plus courante est l&#8217;alop\u00e9cie androg\u00e9n\u00e9tique, qui est caus\u00e9e principalement par des facteurs hormonaux et g\u00e9n\u00e9tiques.\u00a0<br \/>Pour r\u00e9duire durablement la chute de cheveux, des traitements ont\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb4bedd e-flex e-con-boxed e-con e-child\" data-id=\"bb4bedd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61a42ec elementor-widget elementor-widget-text-editor\" data-id=\"61a42ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00e9t\u00e9 \u00e9labor\u00e9s en compl\u00e9ment d\u2019une \u00e9ventuelle prise de m\u00e9dicaments, Minoxidil et Finast\u00e9ride. <br \/>Le PRP cheveux, le LED cheveux et la m\u00e9soth\u00e9rapie capillaire sont des m\u00e9thodes qui am\u00e9liorent la densit\u00e9 des cheveux et en stimulent la repousse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1184d2 e-flex e-con-boxed e-con e-parent\" data-id=\"a1184d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0908a1b e-con-full e-flex e-con e-child\" data-id=\"0908a1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f65730b elementor-widget elementor-widget-image\" data-id=\"f65730b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"680\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/cheveux-sains.webp\" class=\"attachment-medium_large size-medium_large wp-image-5364\" alt=\"photo cheveux\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/cheveux-sains.webp 650w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/cheveux-sains-287x300.webp 287w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/cheveux-sains-11x12.webp 11w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bef0c6b e-con-full e-flex e-con e-child\" data-id=\"bef0c6b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b27e9c elementor-widget elementor-widget-heading\" data-id=\"4b27e9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu\u2019est-ce qui peut provoquer la chute de cheveux ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6a355 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5a6a355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55d4228 elementor-widget elementor-widget-text-editor\" data-id=\"55d4228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>Le cycle du cheveu se compose de trois phases : la phase de croissance ou anag\u00e8ne (85% des cheveux se trouvent dans cette phase), la phase de stabilisation ou catag\u00e8ne\u00a0 (entre 1 et 2% des cheveux se trouvent dans cette phase), la phase de chute ou t\u00e9log\u00e8ne (15% des cheveux se trouvent dans cette phase).<br \/>Lors d\u2019un examen dermatologique du cuir chevelu, l\u2019analyse de ces phases est important pour l\u2019identification d\u2019une \u00e9ventuelle cause.<\/p><p>L\u2019alop\u00e9cie peut \u00eatre aigu\u00eb (si sa dur\u00e9e est inf\u00e9rieure \u00e0 trois mois) ou chronique (si sa dur\u00e9e est sup\u00e9rieure \u00e0 trois mois), diffuse ou localis\u00e9e.<br \/>Les causes d\u2019alop\u00e9cie aigu\u00eb sont : le stress, une perte de poids rapide, une intervention chirurgicale, une infection ou une h\u00e9morragie aigu\u00eb, le post partum.<br \/>Les causes d\u2019alop\u00e9cie chronique sont : les carences (notamment la carence en fer), les troubles endocriniens, l<strong>&#8216;<\/strong>alop\u00e9cie de traction, les insuffisances d\u2019organe, notamment l\u2019insuffisance r\u00e9nale.<br \/>La cause la plus fr\u00e9quente d\u2019alop\u00e9cie est l\u2019<strong>alop\u00e9cie androg\u00e9n\u00e9tique<\/strong>.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-540a769 e-flex e-con-boxed e-con e-parent\" data-id=\"540a769\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7fb02c e-flex e-con-boxed e-con e-child\" data-id=\"f7fb02c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-72ec0fa e-flex e-con-boxed e-con e-child\" data-id=\"72ec0fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8662eb elementor-widget elementor-widget-heading\" data-id=\"d8662eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pilule et chute de cheveux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b343203 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b343203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e94d22 elementor-widget elementor-widget-text-editor\" data-id=\"3e94d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certaines contraceptions ont des effets b\u00e9n\u00e9fiques sur la chevelure, d\u2019autres la fragilisent et peuvent \u00eatre responsables d\u2019alop\u00e9cie.<\/p><h3>Quels effets \u00e0 la contraception sur la chute de cheveux ?<\/h3><p>Les hormones sont importants pour l&#8217;\u00e9tat de sant\u00e9 des cheveux. Ils influencent leur brillance, leur robustesse et leur tendance \u00e0 devenir secs et ternes. Les variations hormonales peuvent causer une <strong>chute de cheveux hormonale<\/strong>. <br \/>La contraception hormonale a un impact direct sur l&#8217;apparence des cheveux. La composition et le dosage en hormones d\u00e9pendent du type de pilule. C&#8217;est pourquoi certaines pilules oestroprogestatives am\u00e9liorent la qualit\u00e9 des cheveux, tandis que les pilules progestatives seules peuvent entra\u00eener leur d\u00e9t\u00e9rioration.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da1a02f e-flex e-con-boxed e-con e-child\" data-id=\"da1a02f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2726e2 elementor-widget elementor-widget-heading\" data-id=\"f2726e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chute de cheveux et h\u00e9r\u00e9dit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53d86af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"53d86af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-148cdaf elementor-widget elementor-widget-text-editor\" data-id=\"148cdaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;alop\u00e9cie peut \u00eatre d\u2019origine h\u00e9r\u00e9ditaire. La forme la plus courante est l&#8217;alop\u00e9cie androg\u00e9n\u00e9tique, qui touche majoritairement les hommes. Contrairement \u00e0 ce que l&#8217;on pourrait penser, elle n&#8217;est pas uniquement li\u00e9e au vieillissement et peut appara\u00eetre d\u00e8s l&#8217;\u00e2ge de 20 ans. Chez les hommes, ce type d&#8217;alop\u00e9cie commence g\u00e9n\u00e9ralement par une perte de cheveux au niveau de la ligne frontale et des tempes.<br \/>Le facteur h\u00e9r\u00e9ditaire joue un r\u00f4le pr\u00e9pond\u00e9rant dans l&#8217;alop\u00e9cie androg\u00e9n\u00e9tique. Cependant, les hormones, notamment les androg\u00e8nes, sont \u00e9galement impliqu\u00e9es. Les r\u00e9cepteurs aux androg\u00e8nes pr\u00e9sents dans la papille dermique du cheveu perturbent le cycle pilaire\u00a0: la croissance des cheveux est acc\u00e9l\u00e9r\u00e9e et les cheveux deviennent de plus en plus fins avant de tomber d\u00e9finitivement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5acea08 e-flex e-con-boxed e-con e-parent\" data-id=\"5acea08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-47adde8 e-flex e-con-boxed e-con e-child\" data-id=\"47adde8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9e44930 e-flex e-con-boxed e-con e-child\" data-id=\"9e44930\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a525d6 elementor-widget elementor-widget-heading\" data-id=\"6a525d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi on perd ses cheveux \u00e0 la m\u00e9nopause ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb587c7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cb587c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a08e19 elementor-widget elementor-widget-image\" data-id=\"6a08e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"384\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-768x384.webp\" class=\"attachment-medium_large size-medium_large wp-image-11116\" alt=\"photo chute cheveux m\u00e9nopause\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-768x384.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-300x150.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-1024x512.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-1536x768.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-2048x1024.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/alopecie-menopause-18x9.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41bf5fc elementor-widget elementor-widget-text-editor\" data-id=\"41bf5fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La perte de cheveux \u00e0 la m\u00e9nopause est principalement due aux changements hormonaux qui se produisent pendant cette p\u00e9riode. \u00c0 la m\u00e9nopause, les niveaux d&#8217;\u0153strog\u00e8nes et de progest\u00e9rone diminuent, l&#8217;\u00e9quilibre hormonal en est perturb\u00e9. La baisse des hormones f\u00e9minines entra\u00eene une augmentation relative des androg\u00e8nes, les hormones masculines, ce qui peut avoir un impact sur les follicules pileux. <br \/>Les androg\u00e8nes, en fait, r\u00e9duisent la taille des follicules pileux, ralentissent la croissance des cheveux et acc\u00e9l\u00e8rent leur chute. <br \/>D&#8217;autres facteurs tels que le stress, les carences nutritionnelles et certains m\u00e9dicaments peuvent contribuer \u00e0 la perte de cheveux \u00e0 la m\u00e9nopause.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c44825d e-flex e-con-boxed e-con e-child\" data-id=\"c44825d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8a959 elementor-widget elementor-widget-heading\" data-id=\"4b8a959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chute de cheveux pendant la grossesse<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9801aa2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9801aa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286b47f elementor-widget elementor-widget-text-editor\" data-id=\"286b47f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La chute de cheveux apr\u00e8s la grossesse, \u00e9galement appel\u00e9e <strong>chute de cheveux post-partum<\/strong>, est un ph\u00e9nom\u00e8ne courant. Environ un tiers des femmes peuvent \u00eatre touch\u00e9es. Ce type de chute de cheveux est hormonale, d\u00e9clench\u00e9e par les changements hormonaux qui surviennent apr\u00e8s l&#8217;accouchement.<br \/>Pendant la grossesse, les futures mamans observent souvent une am\u00e9lioration de la qualit\u00e9 des cheveux qui deviennent plus brillants, soyeux et poussent mieux sous l\u2019effet de l&#8217;augmentation du taux d&#8217;\u0153strog\u00e8nes. <br \/>Apr\u00e8s l&#8217;accouchement, la baisse rapide de cet hormone provoque une chute de cheveux qui peut \u00eatre impressionnante, ce qui peut donner l&#8217;impression de <strong>perdre des poign\u00e9es de cheveux<\/strong>.<br \/>Plusieurs autres facteurs peuvent aggraver la chute de cheveux apr\u00e8s l&#8217;accouchement : la perte de poids rapide, les carences nutritionnelles, notamment en fer, le stress et la fatigue.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-727d165 e-flex e-con-boxed e-con e-parent\" data-id=\"727d165\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-04b645d e-flex e-con-boxed e-con e-child\" data-id=\"04b645d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fd3a351 e-flex e-con-boxed e-con e-child\" data-id=\"fd3a351\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dee850 elementor-widget elementor-widget-heading\" data-id=\"7dee850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alop\u00e9cie cicatricielle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c49fae8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c49fae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06afd77 elementor-widget elementor-widget-text-editor\" data-id=\"06afd77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>L\u2019<strong>alop\u00e9cie cicatricielle <\/strong>est une forme d\u2019alop\u00e9cie localis\u00e9e qui malheureusement est d\u00e9finitive.<br \/>Elle peut \u00eatre provoqu\u00e9e par une inflammation du cuir chevelu ou caus\u00e9e par un traumatisme, une br\u00fblure, une radioth\u00e9rapie du cuir chevelu.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5962273 e-flex e-con-boxed e-con e-child\" data-id=\"5962273\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1290aa9 elementor-widget elementor-widget-heading\" data-id=\"1290aa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chute de cheveux due au stress<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ae2e38 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8ae2e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3da5e74 elementor-widget elementor-widget-text-editor\" data-id=\"3da5e74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette chute des cheveux, \u00e9galement connue sous le nom d\u2019 <strong>effluvium t\u00e9log\u00e8ne post-partum<\/strong>, est caus\u00e9e par un stress physique ou \u00e9motionnel intense.<br \/>En p\u00e9riode de stress, un plus grande pourcentage de cheveux entre pr\u00e9matur\u00e9ment dans la phase de repos (t\u00e9log\u00e8ne) et tombe apr\u00e8s quelques mois. <br \/>Le ph\u00e9nom\u00e8ne est souvent temporaire et r\u00e9versible une fois le facteur de stress \u00e9limin\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04bc744 e-flex e-con-boxed e-con e-parent\" data-id=\"04bc744\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c6f19dc e-flex e-con-boxed e-con e-child\" data-id=\"c6f19dc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-574f5d2 e-flex e-con-boxed e-con e-child\" data-id=\"574f5d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb8ce05 elementor-widget elementor-widget-heading\" data-id=\"bb8ce05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alop\u00e9cie de traction, qu\u2019est-ce que c\u2019est ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc0f26a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bc0f26a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7683e2e elementor-widget elementor-widget-text-editor\" data-id=\"7683e2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>L\u2019alop\u00e9cie de traction est un type d\u2019alop\u00e9cie caus\u00e9e par une tension r\u00e9p\u00e9t\u00e9e et excessive sur les follicules pileux. <br \/>Elle est souvent la cons\u00e9quence de coiffures serr\u00e9es telles que tresses, chignons et queues de cheval.<br \/>Cette tension constante endommage les follicules, entra\u00eenant une perte de cheveux progressive.<br \/>Les premiers signes de l\u2019alop\u00e9cie de traction sont l&#8217;amincissement des cheveux et le recul de la ligne frontale. Pour pr\u00e9venir et traiter cette condition, il est recommand\u00e9 de r\u00e9duire la tension sur les cheveux en \u00e9vitant les coiffures serr\u00e9es.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2cb144 e-flex e-con-boxed e-con e-parent\" data-id=\"e2cb144\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b20d018 e-con-full e-flex e-con e-child\" data-id=\"b20d018\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2dbc52 elementor-widget elementor-widget-heading\" data-id=\"c2dbc52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alop\u00e9cie androg\u00e9n\u00e9tique\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16b16ac elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16b16ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da85701 elementor-widget elementor-widget-text-editor\" data-id=\"da85701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>La cause la plus fr\u00e9quente d\u2019alop\u00e9cie est l\u2019alop\u00e9cie androg\u00e9n\u00e9tique d\u2019origine g\u00e9n\u00e9tique o\u00f9 la chute est due \u00e0 l\u2019influence des androg\u00e8nes.<br \/>Ce type d\u2019alop\u00e9cie peut toucher l\u2019homme \u00e0 partir de 18 ans et la femme d\u00e8s la trentaine.\u00a0<br \/>On parlera d&#8217;<strong>alop\u00e9cie chez l&#8217;homme<\/strong> et d&#8217;<strong>alop\u00e9cie chez la femme<\/strong>.<br \/>Deux \u00e9chelles repr\u00e9sentent les stades d\u2019\u00e9volution du ph\u00e9nom\u00e8ne, l\u2019\u00e9chelle de Hamilton pour l\u2019homme et l\u2019\u00e9chelle de Ludwig pour la femme.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ff3a77 e-flex e-con-boxed e-con e-child\" data-id=\"3ff3a77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-541f230 elementor-widget elementor-widget-image\" data-id=\"541f230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-homme-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-5365\" alt=\"photo gravit\u00e9 calvitie homme\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-homme-768x576.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-homme-300x225.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-homme-16x12.webp 16w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-homme.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cf036 elementor-widget elementor-widget-image\" data-id=\"97cf036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-femme-768x576.webp\" class=\"attachment-medium_large size-medium_large wp-image-5366\" alt=\"photo gravit\u00e9 calvitie femme\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-femme-768x576.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-femme-300x225.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-femme-16x12.webp 16w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/alopecie-femme.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-156ecfe e-flex e-con-boxed e-con e-parent\" data-id=\"156ecfe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8cd3c elementor-widget elementor-widget-heading\" data-id=\"0e8cd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment pr\u00e9venir la chute de cheveux\u00a0?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32317a5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32317a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93fc375 elementor-widget elementor-widget-text-editor\" data-id=\"93fc375\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"110\" data-end=\"253\">La seule v\u00e9ritable pr\u00e9vention consiste \u00e0 traiter la cause de la chute. Toutefois, certains gestes permettent d\u2019am\u00e9liorer la sant\u00e9 des cheveux :<\/p><ul><li data-start=\"255\" data-end=\"577\">Utiliser des shampooings doux, sans sulfates, pour \u00e9viter d\u2019agresser le cuir chevelu.<\/li><li data-start=\"255\" data-end=\"577\">Limiter la fr\u00e9quence des soins chimiques (colorations, permanentes, lissages).<\/li><li data-start=\"255\" data-end=\"577\">Prot\u00e9ger les cheveux des agressions ext\u00e9rieures, notamment des UV.<\/li><li data-start=\"255\" data-end=\"577\">V\u00e9rifier l\u2019absence de carence en fer, souvent impliqu\u00e9e dans la chute de cheveux.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e9e7fb e-flex e-con-boxed e-con e-parent\" data-id=\"0e9e7fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f96c93 elementor-widget elementor-widget-heading\" data-id=\"7f96c93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment stopper la chute de cheveux ? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc31611 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fc31611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8237840 elementor-widget elementor-widget-text-editor\" data-id=\"8237840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La chute de cheveux, chez la femme comme chez l\u2019homme, constitue un motif fr\u00e9quent de consultation.<br \/>Bien qu\u2019il existe des traitements pour r\u00e9duire durablement la chute de cheveux, la repousse est al\u00e9atoire et jamais spectaculaire.<br \/>Certaines techniques m\u00e9dicales, utilis\u00e9es seules ou en combinaison, permettant aux patients de retrouver une chevelure plus dense, plus forte et plus saine.<br \/>Avant d\u2019envisager tout traitement, il est essentiel d\u2019identifier et de corriger une \u00e9ventuelle cause d\u2019alop\u00e9cie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-497a6eb e-flex e-con-boxed e-con e-parent\" data-id=\"497a6eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6d07cd2 e-con-full e-flex e-con e-child\" data-id=\"6d07cd2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7715cca elementor-widget elementor-widget-image\" data-id=\"7715cca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/injections-chute-cheveux-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-5367\" alt=\"photo injection PRP cheveux\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/injections-chute-cheveux-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/injections-chute-cheveux-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/injections-chute-cheveux-18x12.webp 18w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/injections-chute-cheveux.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b19d8c4 e-con-full e-flex e-con e-child\" data-id=\"b19d8c4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa0e9d0 elementor-widget elementor-widget-heading\" data-id=\"fa0e9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PRP cheveux : chevelure parfaite en trois mois<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24960a2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"24960a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0341d2 elementor-widget elementor-widget-text-editor\" data-id=\"b0341d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div id=\"origine-cernes\" class=\"et_pb_section et_pb_section_5 et_pb_with_background et_section_regular et_had_animation\"><div class=\"et_pb_row et_pb_row_6\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_9 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_10 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>Sur le plan esth\u00e9tique, la m\u00e9thode de r\u00e9f\u00e9rence est repr\u00e9sent\u00e9e par les injections de PRP, en particulier le PRP cheveux.\u00a0\u00a0<br \/>Aucune pr\u00e9paration particuli\u00e8re n\u2019est requise avant la s\u00e9ance. Le docteur Romano commence par analyser le cuir chevelu afin d\u2019identifier les zones les plus fragilis\u00e9es, m\u00eame si l\u2019ensemble du cuir chevelu sera trait\u00e9.<br data-start=\"399\" data-end=\"402\" \/>Une prise de sang est r\u00e9alis\u00e9e, puis le tube est centrifug\u00e9 pendant environ six minutes pour s\u00e9parer le plasma riche en plaquettes (PRP) des autres composants sanguins. Le PRP, concentr\u00e9 en facteurs de croissance, est ensuite pr\u00e9lev\u00e9 et inject\u00e9 dans le cuir chevelu selon une technique de m\u00e9soth\u00e9rapie, \u00e0 l\u2019aide d\u2019un pistolet, rendant la s\u00e9ance quasiment indolore.<br data-start=\"766\" data-end=\"769\" \/>Il n\u2019y a pas de suites particuli\u00e8res et la reprise des activit\u00e9s quotidiennes est imm\u00e9diate. En revanche, il est d\u00e9conseill\u00e9 de prendre des anti-inflammatoires ou des cortico\u00efdes dans les 48 heures suivant la s\u00e9ance.<br data-start=\"985\" data-end=\"988\" \/>Le protocole d\u2019attaque comprend trois s\u00e9ances espac\u00e9es de trois mois. Par la suite, une s\u00e9ance d\u2019entretien annuelle est recommand\u00e9e.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a54e38 e-flex e-con-boxed e-con e-parent\" data-id=\"0a54e38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-64d1669 e-con-full e-flex e-con e-child\" data-id=\"64d1669\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6c58f7 elementor-widget elementor-widget-image\" data-id=\"d6c58f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"384\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-768x384.webp\" class=\"attachment-medium_large size-medium_large wp-image-13603\" alt=\"photo injection m\u00e9soth\u00e9rapie cheveux\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-768x384.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-300x150.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-1024x512.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-1536x768.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-2048x1024.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/mesotherapie-cheveux-1-18x9.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e32580a e-con-full e-flex e-con e-child\" data-id=\"e32580a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57216ec elementor-widget elementor-widget-heading\" data-id=\"57216ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e9soth\u00e9rapie cheveux : traitement de la chute de cheveux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd350e1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bd350e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-787f492 elementor-widget elementor-widget-text-editor\" data-id=\"787f492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div id=\"origine-cernes\" class=\"et_pb_section et_pb_section_5 et_pb_with_background et_section_regular et_had_animation\"><div class=\"et_pb_row et_pb_row_6\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_9 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_10 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>La m\u00e9soth\u00e9rapie cheveux consiste \u00e0 injecter directement dans le cuir chevelu un m\u00e9lange de vitamines, min\u00e9raux, acides amin\u00e9s et autres nutriments essentiels. Ces actifs stimulent les follicules pileux, am\u00e9liorent localement la circulation sanguine et favorisent la r\u00e9g\u00e9n\u00e9ration cellulaire. Elle contribue \u00e9galement \u00e0 ralentir la chute de cheveux en renfor\u00e7ant les follicules et en prolongeant leur phase de croissance. Les s\u00e9ances sont bien tol\u00e9r\u00e9es lorsqu\u2019elles sont r\u00e9alis\u00e9es au pistolet ; l\u2019injection manuelle est plus douloureuse et moins efficace.<br data-start=\"670\" data-end=\"673\" \/>Apr\u00e8s la s\u00e9ance, il est recommand\u00e9 d\u2019\u00e9viter le shampooing jusqu\u2019au lendemain, ainsi que toute activit\u00e9 entra\u00eenant une transpiration importante au niveau du cuir chevelu le jour m\u00eame.<br data-start=\"855\" data-end=\"858\" \/>Le protocole comprend une phase d\u2019attaque et une phase d\u2019entretien. La phase d\u2019attaque pr\u00e9voit six s\u00e9ances espac\u00e9es de deux semaines, puis trois s\u00e9ances \u00e0 un mois d\u2019intervalle. La phase d\u2019entretien consiste ensuite en une s\u00e9ance tous les trois \u00e0 six mois.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca4cdb0 e-flex e-con-boxed e-con e-parent\" data-id=\"ca4cdb0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-15a905e e-con-full e-flex e-con e-child\" data-id=\"15a905e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5986c5 elementor-widget elementor-widget-image\" data-id=\"f5986c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-11104\" alt=\"photo traitement LED cheveux\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/led-cheveux-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8dfe22d e-con-full e-flex e-con e-child\" data-id=\"8dfe22d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff06b70 elementor-widget elementor-widget-heading\" data-id=\"ff06b70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Traitement de la perte de cheveux : LED\n cheveux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fff1a11 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fff1a11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23023e4 elementor-widget elementor-widget-text-editor\" data-id=\"23023e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div id=\"origine-cernes\" class=\"et_pb_section et_pb_section_5 et_pb_with_background et_section_regular et_had_animation\"><div class=\"et_pb_row et_pb_row_6\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_9 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_10 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>La th\u00e9rapie par LED (diodes \u00e9lectroluminescentes) est une technique innovante et non invasive pour traiter l&#8217;alop\u00e9cie, dont les r\u00e9sultats sont prometteurs. Cette m\u00e9thode utilise des longueurs d&#8217;onde sp\u00e9cifiques pour stimuler les follicules pileux et favoriser la repousse des cheveux. <br \/>La lumi\u00e8re LED am\u00e9liore la circulation sanguine ce qui augmente l\u2019apport de nutriments essentiels aux niveau des follicules des cheveux. Elle aide \u00e9galement \u00e0 r\u00e9duire l&#8217;inflammation et le stress oxydatif, deux facteurs souvent associ\u00e9s \u00e0 la chute de cheveux. Le traitement par LED est indolore et ne n\u00e9cessite pas de temps de r\u00e9cup\u00e9ration.<br \/>Ce traitement peut \u00eatre r\u00e9alis\u00e9 seul ou en compl\u00e9ment \u00e0 la m\u00e9soth\u00e9rapie et aux s\u00e9ances de PRP.<br \/>Une vingtaine de s\u00e9ances sont n\u00e9cessaires.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7824c9 e-flex e-con-boxed e-con e-parent\" data-id=\"e7824c9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0516f9b elementor-widget elementor-widget-heading\" data-id=\"0516f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9sultats avant \/ apr\u00e8s les traitements de la chute de cheveux <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f98dcaf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f98dcaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1560db1 elementor-widget elementor-widget-text-editor\" data-id=\"1560db1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"118\" data-end=\"1130\">Les r\u00e9sultats commencent \u00e0 \u00eatre visibles environ trois mois apr\u00e8s le d\u00e9but du traitement, car le cycle capillaire est long. Leur importance varie selon la r\u00e9ponse individuelle et la m\u00e9thode utilis\u00e9e.<br data-start=\"317\" data-end=\"320\" \/>La LED am\u00e9liore la circulation sanguine du cuir chevelu, r\u00e9duit l\u2019inflammation et le stress oxydatif, et stimule les follicules pileux. Elle peut augmenter l\u00e9g\u00e8rement la densit\u00e9 et la qualit\u00e9 des cheveux, mais la repousse reste tr\u00e8s limit\u00e9e.<br data-start=\"561\" data-end=\"564\" \/>La m\u00e9soth\u00e9rapie renforce les follicules et prolonge leur phase de croissance gr\u00e2ce \u00e0 l\u2019apport direct de nutriments essentiels. Elle am\u00e9liore la qualit\u00e9 du cheveu, qui devient plus \u00e9pais et plus r\u00e9sistant. Elle r\u00e9duit \u00e9galement la chute, mais le taux de repousse reste faible.<br data-start=\"843\" data-end=\"846\" \/>Le PRP stimule la r\u00e9g\u00e9n\u00e9ration tissulaire et am\u00e9liore la sant\u00e9 des follicules gr\u00e2ce aux facteurs de croissance. Il r\u00e9duit la chute, favorise l\u2019\u00e9paississement des cheveux existants et peut d\u00e9clencher de nouveaux cycles de repousse, avec un taux de repousse variable selon les patients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bea105 e-flex e-con-boxed e-con e-parent\" data-id=\"3bea105\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dfeca2 elementor-widget elementor-widget-heading\" data-id=\"2dfeca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Traitement de la chute des cheveux \u00e0 Gen\u00e8ve : prix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3606124 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3606124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba746e7 elementor-widget elementor-widget-text-editor\" data-id=\"ba746e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 Gen\u00e8ve, les traitements m\u00e9dicaux contre la chute de cheveux sont propos\u00e9s \u00e0 des tarifs qui varient selon la technique utilis\u00e9e. Le PRP (Plasma Riche en Plaquettes), souvent indiqu\u00e9 pour son action cibl\u00e9e sur la densit\u00e9 capillaire, est factur\u00e9 600\u202fCHF par s\u00e9ance. Le protocole de m\u00e9soth\u00e9rapie capillaire, \u00e9galement appel\u00e9 m\u00e9socheveux, est propos\u00e9 \u00e0 200\u202fCHF la s\u00e9ance. Ces prix s\u2019appliquent \u00e0 chaque session, et le nombre de s\u00e9ances n\u00e9cessaires d\u00e9pend du type de perte de cheveux, du terrain de chaque patient et de la strat\u00e9gie th\u00e9rapeutique adopt\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9296b26 e-flex e-con-boxed e-con e-parent\" data-id=\"9296b26\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-048fdd3 elementor-widget elementor-widget-heading\" data-id=\"048fdd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avis sur les traitements pour la chute de  cheveux <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-800f7a2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"800f7a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8571900 elementor-widget elementor-widget-text-editor\" data-id=\"8571900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les patients rapportent une nette am\u00e9lioration de la qualit\u00e9 et de la densit\u00e9 de leurs cheveux, accompagn\u00e9e d\u2019un regain de confiance en eux. Ils appr\u00e9cient le caract\u00e8re non invasif des traitements et l\u2019absence d\u2019\u00e9viction sociale. Beaucoup soulignent que la combinaison de plusieurs techniques donne de meilleurs r\u00e9sultats, \u00e0 condition d\u2019\u00eatre r\u00e9guliers dans le suivi. N\u00e9anmoins, comme pour tout traitement m\u00e9dical, la r\u00e9ponse varie selon les personnes, d\u2019o\u00f9 la n\u00e9cessit\u00e9 d\u2019une \u00e9valuation personnalis\u00e9e par un m\u00e9decin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-515dfda e-flex e-con-boxed e-con e-parent\" data-id=\"515dfda\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ddc775 elementor-widget elementor-widget-heading\" data-id=\"3ddc775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rences m\u00e9dicales sur la chute de cheveux\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9558c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0f9558c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cca4c5f elementor-widget elementor-widget-text-editor\" data-id=\"cca4c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-section-id=\"1lu8qg2\" data-start=\"640\" data-end=\"727\">La croissance des cheveux suit un <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK499948\/\">cycle biologique pr\u00e9cis<\/a>, alternant des phases d\u2019activit\u00e9, de transition et de repos. L\u2019\u00e9quilibre entre ces diff\u00e9rentes \u00e9tapes permet le renouvellement naturel de la chevelure ; lorsqu\u2019il est perturb\u00e9, une augmentation de la chute ou une diminution progressive de la densit\u00e9 capillaire peuvent appara\u00eetre.<\/li><li data-section-id=\"1lu8qg2\" data-start=\"640\" data-end=\"727\">Les follicules pileux sont des structures vivantes dont l\u2019activit\u00e9 d\u00e9pend d\u2019<a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC3412235\/\">interactions complexes entre les cellules sp\u00e9cialis\u00e9es, les signaux hormonaux et l\u2019environnement local du cuir chevelu<\/a>. Comprendre ces m\u00e9canismes permet d\u2019adapter la prise en charge selon l\u2019origine de la perte de cheveux.<\/li><li data-section-id=\"1lu8qg2\" data-start=\"640\" data-end=\"727\">L\u2019alop\u00e9cie androg\u00e9n\u00e9tique est caract\u00e9ris\u00e9e par une <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK430924\/\">miniaturisation progressive des follicules pileux<\/a> sous l\u2019influence de facteurs g\u00e9n\u00e9tiques et hormonaux. Les cheveux deviennent progressivement plus fins, plus courts et moins visibles, entra\u00eenant une diminution de la densit\u00e9 capillaire<\/li><li data-section-id=\"1lu8qg2\" data-start=\"640\" data-end=\"727\">L\u2019effluvium t\u00e9log\u00e8ne correspond \u00e0 une <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK430848\/\">modification temporaire du cycle capillaire<\/a> au cours de laquelle un nombre plus important de cheveux entre en phase de repos. Il peut survenir apr\u00e8s diff\u00e9rents \u00e9v\u00e9nements comme un stress important, une maladie, une variation hormonale ou une p\u00e9riode post-partum.<\/li><li data-section-id=\"1lu8qg2\" data-start=\"640\" data-end=\"727\">Les recommandations de la Soci\u00e9t\u00e9 Fran\u00e7aise de Dermatologie rappellent que la prise en charge d\u2019une chute de cheveux n\u00e9cessite avant tout une <a href=\"https:\/\/dermato-info.fr\/fr\/les-maladies-de-la-peau\/la-chute-de-cheveux\">analyse pr\u00e9cise du cuir chevelu et la recherche d\u2019une cause<\/a> afin de proposer une strat\u00e9gie adapt\u00e9e \u00e0 chaque patient.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb1bae3 e-flex e-con-boxed e-con e-parent\" data-id=\"bb1bae3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4591c3 elementor-widget elementor-widget-heading\" data-id=\"f4591c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes sur le traitement de la chute de cheveux\u00a0\u00e0 Gen\u00e8ve <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b99bee7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b99bee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dc60e0 elementor-widget elementor-widget-n-accordion\" data-id=\"4dc60e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8150\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-8150\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quel est le meilleur traitement pour l'alop\u00e9cie ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8150\" class=\"elementor-element elementor-element-c22c58f e-con-full e-flex e-con e-child\" data-id=\"c22c58f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a10ae7b elementor-widget elementor-widget-text-editor\" data-id=\"a10ae7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le meilleur traitement sera d\u00e9cid\u00e9 en fonction de la cause de l&#8217;alop\u00e9cie, de sa gravit\u00e9 et du genre du patient. Une consultation avec un sp\u00e9cialiste permettra de d\u00e9terminer le traitement le plus adapt\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8151\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8151\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Est-ce que les cheveux repoussent apr\u00e8s 60 ans ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8151\" class=\"elementor-element elementor-element-a7b15a5 e-con-full e-flex e-con e-child\" data-id=\"a7b15a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49ef65f elementor-widget elementor-widget-text-editor\" data-id=\"49ef65f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oui, les cheveux peuvent repousser apr\u00e8s 60 ans, bien que la densit\u00e9 et la vitesse de repousse soient r\u00e9duites. Des traitements tels que le PRP, la m\u00e9soth\u00e9rapie, et la th\u00e9rapie par LED en stimulent la repousse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8152\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8152\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quel est le meilleur produit anti-chute de cheveux pour la femme ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8152\" class=\"elementor-element elementor-element-44c7024 e-con-full e-flex e-con e-child\" data-id=\"44c7024\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93ba702 elementor-widget elementor-widget-text-editor\" data-id=\"93ba702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour les femmes, des produits contenant du Minoxidil sont souvent recommand\u00e9s. Des solutions naturelles comme les huiles essentielles et des compl\u00e9ments alimentaires sont d\u2019appoint.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8153\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8153\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Est-ce que les cheveux repoussent apr\u00e8s une alop\u00e9cie ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8153\" class=\"elementor-element elementor-element-b8b8677 e-flex e-con-boxed e-con e-child\" data-id=\"b8b8677\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d4315 elementor-widget elementor-widget-text-editor\" data-id=\"c4d4315\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oui, les cheveux peuvent repousser apr\u00e8s une alop\u00e9cie, surtout si elle est trait\u00e9e rapidement et efficacement, mais il ne peut pas y avoir de repousse en cas d\u2019alop\u00e9cie cicatricielle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8154\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8154\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quelle plante peut remplacer le Minoxidil ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8154\" class=\"elementor-element elementor-element-6ca2dc3 e-flex e-con-boxed e-con e-child\" data-id=\"6ca2dc3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dacea42 elementor-widget elementor-widget-text-editor\" data-id=\"dacea42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des plantes comme le saw palmetto (palmier nain) sont parfois utilis\u00e9es comme alternatives naturelles au minoxidil pour freiner la chute des cheveux. Le minoxidil reste plus efficace qu\u2019une plante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8155\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8155\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment stopper l'alop\u00e9cie androg\u00e9n\u00e9tique ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8155\" class=\"elementor-element elementor-element-b068169 e-flex e-con-boxed e-con e-child\" data-id=\"b068169\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b415ce elementor-widget elementor-widget-text-editor\" data-id=\"5b415ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;alop\u00e9cie androg\u00e9n\u00e9tique peut \u00eatre frein\u00e9e par des traitements tels que le Minoxidil, le Finast\u00e9ride (chez l\u2019homme), la th\u00e9rapie par LED, la m\u00e9soth\u00e9rapie et le PRP. Un mode de vie sain et une alimentation \u00e9quilibr\u00e9e sont \u00e9galement importants.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8156\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8156\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment cacher l'alop\u00e9cie chez la  femme ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8156\" class=\"elementor-element elementor-element-6fab62a e-flex e-con-boxed e-con e-child\" data-id=\"6fab62a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19b082e elementor-widget elementor-widget-text-editor\" data-id=\"19b082e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il est possible d\u2019utiliser des solutions cosm\u00e9tiques telles que les poudres capillaires, les perruques, les extensions de cheveux ou des coiffures sp\u00e9cifiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8157\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8157\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Est-ce que l'alop\u00e9cie est irr\u00e9versible ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8157\" class=\"elementor-element elementor-element-19b88f5 e-flex e-con-boxed e-con e-child\" data-id=\"19b88f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-508f340 elementor-widget elementor-widget-text-editor\" data-id=\"508f340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certaines formes d&#8217;alop\u00e9cie, l&#8217;alop\u00e9cie cicatricielle par exemple, sont irr\u00e9versibles. Cependant, d&#8217;autres types, comme l&#8217;alop\u00e9cie androg\u00e9n\u00e9tique ou l&#8217;alop\u00e9cie areata, peuvent \u00eatre trait\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8158\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8158\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment stopper la chute de cheveux \u00e0 la m\u00e9nopause ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8158\" class=\"elementor-element elementor-element-be5b4fb e-flex e-con-boxed e-con e-child\" data-id=\"be5b4fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c4f770 elementor-widget elementor-widget-text-editor\" data-id=\"6c4f770\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La chute de cheveux pendant la m\u00e9nopause peut \u00eatre frein\u00e9e par des traitements hormonaux, des compl\u00e9ments alimentaires riches en vitamines et min\u00e9raux, ainsi que des traitements topiques comme le Minoxidil.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-8159\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-8159\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment freiner l'alop\u00e9cie ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-8159\" class=\"elementor-element elementor-element-02c63bf e-flex e-con-boxed e-con e-child\" data-id=\"02c63bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-123ffbe elementor-widget elementor-widget-text-editor\" data-id=\"123ffbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour freiner l&#8217;alop\u00e9cie, il faut suivre un traitement adapt\u00e9\u00a0: Minoxidil, PRP et m\u00e9soth\u00e9rapie. Un mode de vie sain, une alimentation \u00e9quilibr\u00e9e et la r\u00e9duction du stress sont \u00e9galement b\u00e9n\u00e9fiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81510\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"11\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81510\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Est-ce que le Minoxidil marche vraiment ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81510\" class=\"elementor-element elementor-element-d3fe483 e-flex e-con-boxed e-con e-child\" data-id=\"d3fe483\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c5a3bc elementor-widget elementor-widget-text-editor\" data-id=\"3c5a3bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oui, il est cliniquement prouv\u00e9 que le Minoxidil est efficace pour traiter la chute de cheveux et pour en stimuler la repousse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81511\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"12\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81511\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quels sont les inconv\u00e9nients du Minoxidil ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81511\" class=\"elementor-element elementor-element-0f22e06 e-flex e-con-boxed e-con e-child\" data-id=\"0f22e06\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a69edb elementor-widget elementor-widget-text-editor\" data-id=\"9a69edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les possibles effets secondaires du Minoxidil sont\u00a0: les irritations du cuir chevelu, les d\u00e9mangeaisons, l\u2019apparition de poils sur le visage et les mains et rarement des palpitations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81512\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"13\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81512\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment \u00e9paissir les cheveux fins ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81512\" class=\"elementor-element elementor-element-799a965 e-flex e-con-boxed e-con e-child\" data-id=\"799a965\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2baad11 elementor-widget elementor-widget-text-editor\" data-id=\"2baad11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;huile essentielle de romarin est reconnu pour ses propri\u00e9t\u00e9s stimulantes sur la repousse des cheveux. L&#8217;huile essentielle de menthe poivr\u00e9e et l&#8217;huile de lavande sont \u00e9galement b\u00e9n\u00e9fiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81513\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"14\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81513\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment \u00e9paissir les cheveux fins \u00e0 la m\u00e9nopause ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81513\" class=\"elementor-element elementor-element-989c3a9 e-flex e-con-boxed e-con e-child\" data-id=\"989c3a9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a06c3ff elementor-widget elementor-widget-text-editor\" data-id=\"a06c3ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour \u00e9paissir les cheveux fins \u00e0 la m\u00e9nopause la m\u00e9soth\u00e9rapie, le PRP et le Minoxidil sont efficaces. Une alimentation riche en prot\u00e9ines et vitamines est recommand\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81514\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"15\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81514\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quel bilan sanguin pour la perte de cheveux ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81514\" class=\"elementor-element elementor-element-f8f405c e-flex e-con-boxed e-con e-child\" data-id=\"f8f405c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef7b3e7 elementor-widget elementor-widget-text-editor\" data-id=\"ef7b3e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un bilan sanguin pour la perte de cheveux doit inclure les dosages de fer, de ferritine, de vitamine D, de vitamine B12, de zinc, des hormones thyro\u00efdiennes et des androg\u00e8nes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81515\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"16\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81515\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quand s\u2019inqui\u00e9ter de la chute de cheveux ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81515\" class=\"elementor-element elementor-element-811fd6c e-flex e-con-boxed e-con e-child\" data-id=\"811fd6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83b6d43 elementor-widget elementor-widget-text-editor\" data-id=\"83b6d43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quand la perte journali\u00e8re de cheveux d\u00e9passe la perte physiologique, c\u2019est-\u00e0-dire 50-100 cheveux par jour, il est temps de consulter un m\u00e9decin. Les signes qui peuvent inqui\u00e9ter sont la perte de densit\u00e9 capillaire, les plaques de calvitie, les d\u00e9mangeaisons ou les irritations du cuir chevelu.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81516\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"17\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81516\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment traiter l'alop\u00e9cie chez la femme naturellement ?  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81516\" class=\"elementor-element elementor-element-19efe5e e-flex e-con-boxed e-con e-child\" data-id=\"19efe5e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b200b2c elementor-widget elementor-widget-text-editor\" data-id=\"b200b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Certaines habitudes sont b\u00e9n\u00e9fiques pour le cuir chevelu, mais elles ne peuvent pas traiter l\u2019alop\u00e9cie\u00a0: massages du cuir chevelu, application de huiles essentielles sur le scalp, compl\u00e9ments alimentaires, alimentation saine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-81517\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"18\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-81517\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment r\u00e9cup\u00e9rer de la masse de cheveux ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-81517\" class=\"elementor-element elementor-element-13aba64 e-flex e-con-boxed e-con e-child\" data-id=\"13aba64\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fae93ec elementor-widget elementor-widget-text-editor\" data-id=\"fae93ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alimentation : aliments riches en prot\u00e9ines, vitamines (biotine, vitamines A, C, D, E) et min\u00e9raux (fer, zinc, s\u00e9l\u00e9nium) et une bonne hydratation.<br \/>Soins capillaires : utilisation de produits capillaires doux sans sulfates, parab\u00e8nes ni silicones. \u00c9viter l&#8217;utilisation excessive de chaleur (s\u00e8che-cheveux, fers \u00e0 lisser) et les coiffures trop serr\u00e9es.<br \/>Traitements m\u00e9dicaux si prescription m\u00e9dicale\u00a0: Minoxidil et Finast\u00e9ride.<br \/>Rem\u00e8des naturels\u00a0: huiles essentielles comme l&#8217;huile de romarin.<br \/>Compl\u00e9ments alimentaires contenant de la biotine et des vitamines.<br \/>PRP cheveux, m\u00e9soth\u00e9rapie cheveux, LED.<br \/>Gestion du stress.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Quel est le meilleur traitement pour l'alop\\u00e9cie ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le meilleur traitement sera d\\u00e9cid\\u00e9 en fonction de la cause de l&#8217;alop\\u00e9cie, de sa gravit\\u00e9 et du genre du patient. Une consultation avec un sp\\u00e9cialiste permettra de d\\u00e9terminer le traitement le plus adapt\\u00e9.\"}},{\"@type\":\"Question\",\"name\":\"Est-ce que les cheveux repoussent apr\\u00e8s 60 ans ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oui, les cheveux peuvent repousser apr\\u00e8s 60 ans, bien que la densit\\u00e9 et la vitesse de repousse soient r\\u00e9duites. Des traitements tels que le PRP, la m\\u00e9soth\\u00e9rapie, et la th\\u00e9rapie par LED en stimulent la repousse.\"}},{\"@type\":\"Question\",\"name\":\"Quel est le meilleur produit anti-chute de cheveux pour la femme ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Pour les femmes, des produits contenant du Minoxidil sont souvent recommand\\u00e9s. Des solutions naturelles comme les huiles essentielles et des compl\\u00e9ments alimentaires sont d\\u2019appoint.\"}},{\"@type\":\"Question\",\"name\":\"Est-ce que les cheveux repoussent apr\\u00e8s une alop\\u00e9cie ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oui, les cheveux peuvent repousser apr\\u00e8s une alop\\u00e9cie, surtout si elle est trait\\u00e9e rapidement et efficacement, mais il ne peut pas y avoir de repousse en cas d\\u2019alop\\u00e9cie cicatricielle.\"}},{\"@type\":\"Question\",\"name\":\"Quelle plante peut remplacer le Minoxidil ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Des plantes comme le saw palmetto (palmier nain) sont parfois utilis\\u00e9es comme alternatives naturelles au minoxidil pour freiner la chute des cheveux. Le minoxidil reste plus efficace qu\\u2019une plante.\"}},{\"@type\":\"Question\",\"name\":\"Comment stopper l'alop\\u00e9cie androg\\u00e9n\\u00e9tique ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"L&#8217;alop\\u00e9cie androg\\u00e9n\\u00e9tique peut \\u00eatre frein\\u00e9e par des traitements tels que le Minoxidil, le Finast\\u00e9ride (chez l\\u2019homme), la th\\u00e9rapie par LED, la m\\u00e9soth\\u00e9rapie et le PRP. Un mode de vie sain et une alimentation \\u00e9quilibr\\u00e9e sont \\u00e9galement importants.\"}},{\"@type\":\"Question\",\"name\":\"Comment cacher l'alop\\u00e9cie chez la  femme ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il est possible d\\u2019utiliser des solutions cosm\\u00e9tiques telles que les poudres capillaires, les perruques, les extensions de cheveux ou des coiffures sp\\u00e9cifiques.\"}},{\"@type\":\"Question\",\"name\":\"Est-ce que l'alop\\u00e9cie est irr\\u00e9versible ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Certaines formes d&#8217;alop\\u00e9cie, l&#8217;alop\\u00e9cie cicatricielle par exemple, sont irr\\u00e9versibles. Cependant, d&#8217;autres types, comme l&#8217;alop\\u00e9cie androg\\u00e9n\\u00e9tique ou l&#8217;alop\\u00e9cie areata, peuvent \\u00eatre trait\\u00e9es.\"}},{\"@type\":\"Question\",\"name\":\"Comment stopper la chute de cheveux \\u00e0 la m\\u00e9nopause ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"La chute de cheveux pendant la m\\u00e9nopause peut \\u00eatre frein\\u00e9e par des traitements hormonaux, des compl\\u00e9ments alimentaires riches en vitamines et min\\u00e9raux, ainsi que des traitements topiques comme le Minoxidil.\"}},{\"@type\":\"Question\",\"name\":\"Comment freiner l'alop\\u00e9cie ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Pour freiner l&#8217;alop\\u00e9cie, il faut suivre un traitement adapt\\u00e9\\u00a0: Minoxidil, PRP et m\\u00e9soth\\u00e9rapie. Un mode de vie sain, une alimentation \\u00e9quilibr\\u00e9e et la r\\u00e9duction du stress sont \\u00e9galement b\\u00e9n\\u00e9fiques.\"}},{\"@type\":\"Question\",\"name\":\"Est-ce que le Minoxidil marche vraiment ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Oui, il est cliniquement prouv\\u00e9 que le Minoxidil est efficace pour traiter la chute de cheveux et pour en stimuler la repousse.\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les inconv\\u00e9nients du Minoxidil ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Les possibles effets secondaires du Minoxidil sont\\u00a0: les irritations du cuir chevelu, les d\\u00e9mangeaisons, l\\u2019apparition de poils sur le visage et les mains et rarement des palpitations.\"}},{\"@type\":\"Question\",\"name\":\"Comment \\u00e9paissir les cheveux fins ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"L&#8217;huile essentielle de romarin est reconnu pour ses propri\\u00e9t\\u00e9s stimulantes sur la repousse des cheveux. L&#8217;huile essentielle de menthe poivr\\u00e9e et l&#8217;huile de lavande sont \\u00e9galement b\\u00e9n\\u00e9fiques.\"}},{\"@type\":\"Question\",\"name\":\"Comment \\u00e9paissir les cheveux fins \\u00e0 la m\\u00e9nopause ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Pour \\u00e9paissir les cheveux fins \\u00e0 la m\\u00e9nopause la m\\u00e9soth\\u00e9rapie, le PRP et le Minoxidil sont efficaces. Une alimentation riche en prot\\u00e9ines et vitamines est recommand\\u00e9e.\"}},{\"@type\":\"Question\",\"name\":\"Quel bilan sanguin pour la perte de cheveux ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Un bilan sanguin pour la perte de cheveux doit inclure les dosages de fer, de ferritine, de vitamine D, de vitamine B12, de zinc, des hormones thyro\\u00efdiennes et des androg\\u00e8nes.\"}},{\"@type\":\"Question\",\"name\":\"Quand s\\u2019inqui\\u00e9ter de la chute de cheveux ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Quand la perte journali\\u00e8re de cheveux d\\u00e9passe la perte physiologique, c\\u2019est-\\u00e0-dire 50-100 cheveux par jour, il est temps de consulter un m\\u00e9decin. Les signes qui peuvent inqui\\u00e9ter sont la perte de densit\\u00e9 capillaire, les plaques de calvitie, les d\\u00e9mangeaisons ou les irritations du cuir chevelu.\"}},{\"@type\":\"Question\",\"name\":\"Comment traiter l'alop\\u00e9cie chez la femme naturellement ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Certaines habitudes sont b\\u00e9n\\u00e9fiques pour le cuir chevelu, mais elles ne peuvent pas traiter l\\u2019alop\\u00e9cie\\u00a0: massages du cuir chevelu, application de huiles essentielles sur le scalp, compl\\u00e9ments alimentaires, alimentation saine.\"}},{\"@type\":\"Question\",\"name\":\"Comment r\\u00e9cup\\u00e9rer de la masse de cheveux ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Alimentation : aliments riches en prot\\u00e9ines, vitamines (biotine, vitamines A, C, D, E) et min\\u00e9raux (fer, zinc, s\\u00e9l\\u00e9nium) et une bonne hydratation.Soins capillaires : utilisation de produits capillaires doux sans sulfates, parab\\u00e8nes ni silicones. \\u00c9viter l&#8217;utilisation excessive de chaleur (s\\u00e8che-cheveux, fers \\u00e0 lisser) et les coiffures trop serr\\u00e9es.Traitements m\\u00e9dicaux si prescription m\\u00e9dicale\\u00a0: Minoxidil et Finast\\u00e9ride.Rem\\u00e8des naturels\\u00a0: huiles essentielles comme l&#8217;huile de romarin.Compl\\u00e9ments alimentaires contenant de la biotine et des vitamines.PRP cheveux, m\\u00e9soth\\u00e9rapie cheveux, LED.Gestion du stress.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93e476b e-con-full e-flex e-con e-parent\" data-id=\"93e476b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8565761 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8565761\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d552f elementor-widget elementor-widget-heading\" data-id=\"68d552f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Autres Zones \u00c0  Traiter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d3b590 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6d3b590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c87745 e-con-full e-flex e-con e-child\" data-id=\"2c87745\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2ea574d e-flex e-con-boxed e-con e-child\" data-id=\"2ea574d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-402d8e8 elementor-widget elementor-widget-heading\" data-id=\"402d8e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/coup-eclat-visage\/\">Coup d'\u00e9clat <\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecabc90 e-flex e-con-boxed e-con e-child\" data-id=\"ecabc90\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43b49dd elementor-widget elementor-widget-heading\" data-id=\"43b49dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/red-carpet\/\">Red Carpet<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6fa0098 e-flex e-con-boxed e-con e-child\" data-id=\"6fa0098\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3408963 elementor-widget elementor-widget-heading\" data-id=\"3408963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/skin-prevent\/\">Skin Prevent<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-525de41 e-flex e-con-boxed e-con e-child\" data-id=\"525de41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1789f8e elementor-widget elementor-widget-heading\" data-id=\"1789f8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/skin-restore\/\">Skin Restore<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f338e96 e-flex e-con-boxed e-con e-child\" data-id=\"f338e96\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8294aac elementor-widget elementor-widget-heading\" data-id=\"8294aac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/skin-training\/\">Skin Training<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c34b81 e-con-full e-flex e-con e-child\" data-id=\"5c34b81\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc8f0e9 elementor-widget elementor-widget-heading\" data-id=\"cc8f0e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/beaute-asiatique\/peau-deesse-coreenne\/\">Peau de d\u00e9esse cor\u00e9enne<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdabe59 e-con-full e-flex e-con e-child\" data-id=\"bdabe59\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7090829 elementor-widget elementor-widget-heading\" data-id=\"7090829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/xanthelasma\/\">Xanthelasma<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75806d4 e-con-full e-flex e-con e-parent\" data-id=\"75806d4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-430b492 e-con-full e-flex e-con e-child\" data-id=\"430b492\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-f4ce538 e-flex e-con-boxed e-con e-child\" data-id=\"f4ce538\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e06485 elementor-widget elementor-widget-heading\" data-id=\"9e06485\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/cicatrices\/\">Cicatrices<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc1e272 e-flex e-con-boxed e-con e-child\" data-id=\"fc1e272\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db1c097 elementor-widget elementor-widget-heading\" data-id=\"db1c097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/vergetures\/\">Vergetures<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08ab585 e-flex e-con-boxed e-con e-child\" data-id=\"08ab585\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5bf9c4 elementor-widget elementor-widget-heading\" data-id=\"f5bf9c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/taches\/\">Pigmentations<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6222e13 e-flex e-con-boxed e-con e-child\" data-id=\"6222e13\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cafe7cb elementor-widget elementor-widget-heading\" data-id=\"cafe7cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/taches-de-rousseur\/\">Taches de rousseur<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4338a1d e-flex e-con-boxed e-con e-child\" data-id=\"4338a1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82e0881 elementor-widget elementor-widget-heading\" data-id=\"82e0881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/melasma\/\">M\u00e9lasma<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a686e2c e-con-full e-flex e-con e-child\" data-id=\"a686e2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-019cae4 elementor-widget elementor-widget-heading\" data-id=\"019cae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/taches-de-soleil\/\">Taches de soleil<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CHUTE DE CHEVEUX : SOINS M\u00c9DICAUX CAPILLAIRES Qu\u2019est-ce que c\u2019est la chute de cheveux ? Les cheveux sont un symbole de s\u00e9duction, de sant\u00e9 et de vitalit\u00e9. Chaque individu poss\u00e8de en moyenne entre 80 000 et 160 000 cheveux, qui se renouvellent naturellement sur un cycle de 3 \u00e0 5 ans. Il est normal d\u2019en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":168,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-468","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alop\u00e9cie androg\u00e9n\u00e9tique : causes, sympt\u00f4mes, traitements \u2013 Dr Romano<\/title>\n<meta name=\"description\" content=\"Comment faire repousser les cheveux \u00e0 Gen\u00e8ve ? Les traitements disponibles sont : m\u00e9soth\u00e9rapie cheveux, PRP cheveux, laser, LED et carboxyth\u00e9rapie pour la perte de cheveux. Explications du dr Romano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drromanovaleria.ch\/en\/needs\/skin-and-hair\/alopecia\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alop\u00e9cie androg\u00e9n\u00e9tique : causes, sympt\u00f4mes, traitements \u2013 Dr Romano\" \/>\n<meta property=\"og:description\" content=\"Comment faire repousser les cheveux \u00e0 Gen\u00e8ve ? Les traitements disponibles sont : m\u00e9soth\u00e9rapie cheveux, PRP cheveux, laser, LED et carboxyth\u00e9rapie pour la perte de cheveux. Explications du dr Romano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drromanovaleria.ch\/en\/needs\/skin-and-hair\/alopecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Romano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T12:40:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/\",\"name\":\"Alop\u00e9cie androg\u00e9n\u00e9tique : causes, sympt\u00f4mes, traitements \u2013 Dr Romano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/beaux-cheveux.webp\",\"datePublished\":\"2024-12-30T23:51:14+00:00\",\"dateModified\":\"2026-06-25T12:40:45+00:00\",\"description\":\"Comment faire repousser les cheveux \u00e0 Gen\u00e8ve ? Les traitements disponibles sont : m\u00e9soth\u00e9rapie cheveux, PRP cheveux, laser, LED et carboxyth\u00e9rapie pour la perte de cheveux. Explications du dr Romano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/beaux-cheveux.webp\",\"contentUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/beaux-cheveux.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/alopecie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Besoins\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peau &#038; cheveux\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/besoins\\\/peau-et-cheveux\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Alop\u00e9cie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/\",\"name\":\"Dr Romano\",\"description\":\"M\u00e9decine morphologique et anti-\u00e2ge\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drromanovaleria.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Androgenetic alopecia : causes, symptoms, treatments \u2013 Dr Romano","description":"How to Regrow Hair in Geneva? Available treatments include hair mesotherapy, PRP for hair, laser, LED, and carboxytherapy for hair loss. Explanations by Dr. Romano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drromanovaleria.ch\/en\/needs\/skin-and-hair\/alopecia\/","og_locale":"en_GB","og_type":"article","og_title":"Alop\u00e9cie androg\u00e9n\u00e9tique : causes, sympt\u00f4mes, traitements \u2013 Dr Romano","og_description":"Comment faire repousser les cheveux \u00e0 Gen\u00e8ve ? Les traitements disponibles sont : m\u00e9soth\u00e9rapie cheveux, PRP cheveux, laser, LED et carboxyth\u00e9rapie pour la perte de cheveux. Explications du dr Romano","og_url":"https:\/\/drromanovaleria.ch\/en\/needs\/skin-and-hair\/alopecia\/","og_site_name":"Dr Romano","article_modified_time":"2026-06-25T12:40:45+00:00","og_image":[{"width":280,"height":245,"url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/","url":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/","name":"Androgenetic alopecia : causes, symptoms, treatments \u2013 Dr Romano","isPartOf":{"@id":"https:\/\/drromanovaleria.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/#primaryimage"},"image":{"@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/#primaryimage"},"thumbnailUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp","datePublished":"2024-12-30T23:51:14+00:00","dateModified":"2026-06-25T12:40:45+00:00","description":"How to Regrow Hair in Geneva? Available treatments include hair mesotherapy, PRP for hair, laser, LED, and carboxytherapy for hair loss. Explanations by Dr. Romano.","breadcrumb":{"@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/#primaryimage","url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp","contentUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/beaux-cheveux.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/alopecie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/drromanovaleria.ch\/"},{"@type":"ListItem","position":2,"name":"Besoins","item":"https:\/\/drromanovaleria.ch\/besoins\/"},{"@type":"ListItem","position":3,"name":"Peau &#038; cheveux","item":"https:\/\/drromanovaleria.ch\/besoins\/peau-et-cheveux\/"},{"@type":"ListItem","position":4,"name":"Alop\u00e9cie"}]},{"@type":"WebSite","@id":"https:\/\/drromanovaleria.ch\/#website","url":"https:\/\/drromanovaleria.ch\/","name":"Dr Romano","description":"Morphological and anti-ageing medicine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drromanovaleria.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":5,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/468\/revisions"}],"predecessor-version":[{"id":71293,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/468\/revisions\/71293"}],"up":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/168"}],"wp:attachment":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/media?parent=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}