{"id":19478,"date":"2024-11-17T07:56:49","date_gmt":"2024-11-17T05:56:49","guid":{"rendered":"https:\/\/drromanovaleria.ch\/?page_id=19478"},"modified":"2026-06-25T09:38:11","modified_gmt":"2026-06-25T07:38:11","slug":"asian-eyes","status":"publish","type":"page","link":"https:\/\/drromanovaleria.ch\/en\/beaute-asiatique\/yeux-brides\/","title":{"rendered":"Asian eye"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19478\" class=\"elementor elementor-19478\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdbaa7 e-flex e-con-boxed e-con e-parent\" data-id=\"0bdbaa7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a54c762 e-con-full e-flex e-con e-child\" data-id=\"a54c762\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea9f94 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0ea9f94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OCCIDENTALISATION DE L' \u0152IL ASIATIQUE SANS CHIRURGIE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c1e0b2 elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"3c1e0b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/drromanovaleria.ch\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-454a27d e-flex e-con-boxed e-con e-parent\" data-id=\"454a27d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4936273 e-flex e-con-boxed e-con e-child\" data-id=\"4936273\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9888632 e-con-full e-flex e-con e-child\" data-id=\"9888632\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e2527 elementor-widget elementor-widget-heading\" data-id=\"e9e2527\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu'est-ce que l\u2019Occidentalisation de l\u2019\u0153il asiatique ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0cced6 elementor-widget elementor-widget-text-editor\" data-id=\"c0cced6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019occidentalisation de l\u2019\u0153il consiste principalement \u00e0 modifier subtilement les contours et les proportions de la paupi\u00e8re et du pli de l\u2019\u0153il, afin de cr\u00e9er un regard plus ouvert et d\u2019ajouter de la profondeur au regard. La demande donc, n&#8217;est pas d&#8217;avoir un \u0153il caucasien.<br \/>Ce type de traitement est tr\u00e8s demand\u00e9 par des patients d\u2019origine asiatique qui souhaitent une modification discr\u00e8te sans avoir recours \u00e0 la chirurgie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a250811 e-flex e-con-boxed e-con e-child\" data-id=\"a250811\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-909787e elementor-widget elementor-widget-image\" data-id=\"909787e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-13693\" alt=\"\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-2048x1365.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a4724 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"14a4724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/drromanovaleria.ch\/contactez-le-dr-romano\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prendre rendez-vous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04a446d e-flex e-con-boxed e-con e-parent\" data-id=\"04a446d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e0882c elementor-toc--content-ellipsis elementor-toc--minimized-on-desktop elementor-widget elementor-widget-table-of-contents\" data-id=\"1e0882c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;minimized_on&quot;:&quot;desktop&quot;,&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tSommaire\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__1e0882c\" aria-expanded=\"true\" aria-label=\"Open table of contents\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__1e0882c\" aria-expanded=\"true\" aria-label=\"Close table of contents\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__1e0882c\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa9dd3f e-flex e-con-boxed e-con e-parent\" data-id=\"aa9dd3f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d038ac6 elementor-widget elementor-widget-heading\" data-id=\"d038ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Points forts<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f165dd1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f165dd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6043f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc6043f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0182bd elementor-widget elementor-widget-text-editor\" data-id=\"c0182bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Occidentalisation de l&#8217;\u0153il asiatique \u00e0 Gen\u00e8ve\u00a0<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f48a29d e-flex e-con-boxed e-con e-child\" data-id=\"f48a29d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-579f2ec e-flex e-con-boxed e-con e-child\" data-id=\"579f2ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf5fa83 elementor-widget elementor-widget-text-editor\" data-id=\"bf5fa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La correction non chirurgicale de l&#8217;\u0153il asiatique, souvent appel\u00e9e occidentalisation de l&#8217;\u0153il, est une solution de plus en plus recherch\u00e9e pour obtenir un regard plus ouvert et d\u00e9fini sans subir une intervention chirurgicale. Gr\u00e2ce aux injections de toxine botulique*, d&#8217;acide hyaluronique et au lifting non chirurgical, il est d\u00e9sormais\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-131b23f e-flex e-con-boxed e-con e-child\" data-id=\"131b23f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-adee6c0 elementor-widget elementor-widget-text-editor\" data-id=\"adee6c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>possible\u00a0de modifier subtilement la forme des yeux, rehausser la paupi\u00e8re et accentuer le pli palp\u00e9bral. L\u2019 approche esth\u00e9tique moderne permet une transformation douce et naturelle, adapt\u00e9e aux sp\u00e9cificit\u00e9s du visage asiatique, sans risques ni temps de r\u00e9cup\u00e9ration.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cb0e9e e-flex e-con-boxed e-con e-parent\" data-id=\"3cb0e9e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9966471 elementor-widget elementor-widget-heading\" data-id=\"9966471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diff\u00e9rences anatomiques entre l'\u0153il asiatique et l'\u0153il europ\u00e9en  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d850e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d0d850e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2468bd elementor-widget elementor-widget-text-editor\" data-id=\"a2468bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les diff\u00e9rences anatomiques entre l\u2019\u0153il caucasien et l\u2019\u0153il asiatique sont celles qui concernent les paupi\u00e8res, le pli palp\u00e9bral et la disposition des tissus autour de l\u2019orbite.<\/p><p>Paupi\u00e8re sup\u00e9rieure asiatique : chez les caucasiens, le pli palp\u00e9bral sup\u00e9rieur est g\u00e9n\u00e9ralement bien d\u00e9fini et situ\u00e9 \u00e0 environ 8 \u00e0 12 mm au-dessus de la ligne des cils, ce qui cr\u00e9e un relief plus accentu\u00e9 de la paupi\u00e8re. Chez les asiatiques, ce pli est souvent moins visible, voire absent, donnant \u00e0 la paupi\u00e8re un aspect plus lisse.<br \/>La paupi\u00e8re sup\u00e9rieure asiatique est caract\u00e9ris\u00e9e par : une quantit\u00e9 de graisse orbitaire plus abondante ; un septum qui s&#8217;ins\u00e8re tr\u00e8s bas, avec l&#8217;apon\u00e9vrose du releveur, sous le rebord sup\u00e9rieur du tarse. Il n&#8217;y a pas d&#8217;attaches entre les expansions de l&#8217;apon\u00e9vrose du releveur et la peau ; une peau palp\u00e9brale tr\u00e8s \u00e9lastique ; une fente palp\u00e9brale qui para\u00eet r\u00e9tr\u00e9cie ; un pli palp\u00e9bral sup\u00e9rieur peu marqu\u00e9 voire absent et qui est situ\u00e9 tr\u00e8s bas, pr\u00e8s de la ligne des cils.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a37f8a elementor-widget elementor-widget-image\" data-id=\"4a37f8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-13693\" alt=\"\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-2048x1365.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1978662 elementor-widget elementor-widget-text-editor\" data-id=\"1978662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9picanthus : la conjugaison de la laxit\u00e9 cutan\u00e9e et la position basse (ou l&#8217;absence) du pli palp\u00e9bral sup\u00e9rieur cr\u00e9ent un repli cutan\u00e9 canthal m\u00e9dial, l&#8217;\u00e9picanthus. Il existe quatre stades d&#8217;\u00e9picanthus suivant l&#8217;importance du repli de peau pr\u00e9tarsale au niveau du canthus.<\/p><p>Paupi\u00e8re inf\u00e9rieure asiatique : l&#8217;insertion du septum est haute, pr\u00e8s de la ligne ciliaire ; le muscle palp\u00e9bral est moins \u00e9pais \u00e0 ce niveau ; les poches graisseuses apparaissent pr\u00e9cocement, mais sont stables dans le temps.<\/p><p>On distingue diff\u00e9rents types de plis palp\u00e9braux sup\u00e9rieurs :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f32e81e e-con-full e-flex e-con e-child\" data-id=\"f32e81e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-b168a62 e-flex e-con-boxed e-con e-child\" data-id=\"b168a62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e3c36 elementor-widget elementor-widget-image\" data-id=\"f2e3c36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"387\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-768x387.webp\" class=\"attachment-medium_large size-medium_large wp-image-20003\" alt=\"photo \u0153il asiatique sans pli palp\u00e9bral\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-768x387.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-300x151.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-1024x515.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-1536x773.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-2048x1031.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-absent-18x9.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fefe05 elementor-widget elementor-widget-text-editor\" data-id=\"6fefe05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_4 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Absence de pli palp\u00e9bral sup\u00e9rieur : monopaupi\u00e8re<\/strong><br \/>Il n&#8217;existe pas de pli qui divise la paupi\u00e8re sup\u00e9rieure en deux.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64c419f e-flex e-con-boxed e-con e-child\" data-id=\"64c419f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ae0264 elementor-widget elementor-widget-image\" data-id=\"2ae0264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-20004\" alt=\"photo \u0153il asiatique pli palp\u00e9bral d\u00e9gressif\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-2048x1365.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressi-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71cbd87 elementor-widget elementor-widget-text-editor\" data-id=\"71cbd87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_6 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Pli palp\u00e9bral sup\u00e9rieur d\u00e9gressif avec \u00e9vasement lat\u00e9ral<\/strong><br \/>La partie externe de la paupi\u00e8re en dessous du pli est plus large que l&#8217;interne. <\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5ea5f7 e-flex e-con-boxed e-con e-child\" data-id=\"e5ea5f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8194802 elementor-widget elementor-widget-image\" data-id=\"8194802\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-768x432.webp\" class=\"attachment-medium_large size-medium_large wp-image-20005\" alt=\"photo \u0153il asiatique plis palp\u00e9braux multiples\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-768x432.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-300x169.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-1024x576.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-1536x864.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-2048x1152.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-multiples-18x10.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1908aef elementor-widget elementor-widget-text-editor\" data-id=\"1908aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_8 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Plis palp\u00e9braux sup\u00e9rieurs multiples<\/strong><br \/>Il existe plusieurs plis palp\u00e9braux qui divisent la paupi\u00e8re sup\u00e9rieure.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9afde1b e-con-full e-flex e-con e-child\" data-id=\"9afde1b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-89f0629 e-flex e-con-boxed e-con e-child\" data-id=\"89f0629\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-061eaa2 elementor-widget elementor-widget-image\" data-id=\"061eaa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"349\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-768x349.webp\" class=\"attachment-medium_large size-medium_large wp-image-20006\" alt=\"photo \u0153il asiatique plis palp\u00e9braux parall\u00e8les\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-768x349.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-300x136.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-1024x466.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-1536x698.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-2048x931.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-palpebraux-paralleles-18x8.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6f95e elementor-widget elementor-widget-text-editor\" data-id=\"7c6f95e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_4 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Pli palp\u00e9bral sup\u00e9rieur parall\u00e8le<\/strong><br \/>Le pli est parall\u00e8le au rebord ciliaire, la partie interne de la paupi\u00e8re en dessous du pli a la m\u00eame largeur que l&#8217;externe.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-037330f e-flex e-con-boxed e-con e-child\" data-id=\"037330f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1116b2d elementor-widget elementor-widget-image\" data-id=\"1116b2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-20007\" alt=\"photo \u0153il asiatique plis palp\u00e9bral partiel\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-2048x1366.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-plis-paupiere-partiel-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e72c13 elementor-widget elementor-widget-text-editor\" data-id=\"8e72c13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_6 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Pli palp\u00e9bral sup\u00e9rieur partiel<\/strong><br \/>Le pli palp\u00e9bral sup\u00e9rieur n&#8217;est pas pr\u00e9sent sur toute la longueur de la paupi\u00e8re sup\u00e9rieure.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32ad9b5 e-flex e-con-boxed e-con e-child\" data-id=\"32ad9b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cf11a4 elementor-widget elementor-widget-image\" data-id=\"9cf11a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"511\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-768x511.webp\" class=\"attachment-medium_large size-medium_large wp-image-20008\" alt=\"photo \u0153il asiatique plis palp\u00e9bral sup\u00e9rieur\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-768x511.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-1024x682.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-1536x1022.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-2048x1363.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/11\/oeil-asiatique-pli-palpebral-degressif-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e763489 elementor-widget elementor-widget-text-editor\" data-id=\"e763489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_module et_pb_text et_pb_text_8 et_pb_text_align_center et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><strong>Pli palp\u00e9bral sup\u00e9rieur d\u00e9gressif<\/strong><br \/>Le pli palp\u00e9bral sup\u00e9rieur devient plus \u00e9troit au niveau du canthus interne de l&#8217;\u0153il.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8b286b e-flex e-con-boxed e-con e-parent\" data-id=\"f8b286b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6905474 elementor-widget elementor-widget-heading\" data-id=\"6905474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u2019occidentalisation de l\u2019\u0153il asiatique sans chirurgie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cba68cd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cba68cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e072428 elementor-widget elementor-widget-text-editor\" data-id=\"e072428\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En m\u00e9decine \u00e0 vis\u00e9e esth\u00e9tique, plusieurs techniques permettent de r\u00e9aliser cette transformation de mani\u00e8re douce et non invasive.\u00a0<br \/>Il est important de consulter un m\u00e9decin exp\u00e9riment\u00e9 qui sera en mesure de r\u00e9aliser ces traitements avec une ma\u00eetrise des techniques et une compr\u00e9hension des subtilit\u00e9s morphologiques des visages asiatiques. En choisissant un m\u00e9decin exp\u00e9riment\u00e9, vous b\u00e9n\u00e9ficiez d\u2019un conseil personnalis\u00e9 et d\u2019un traitement sur-mesure, pour des r\u00e9sultats naturels et harmonieux.<\/p><h3>\u00c0 qui s\u2019adresse cette intervention ?<\/h3><p>L\u2019occidentalisation du regard par des techniques de m\u00e9decine esth\u00e9tique convient particuli\u00e8rement aux personnes d\u2019origine asiatique qui souhaitent agrandir et ouvrir le regard, tout en pr\u00e9servant leur identit\u00e9 et leur singularit\u00e9. Ce traitement est id\u00e9al pour ceux qui cherchent une alternative \u00e0 la chirurgie et qui souhaitent des modifications progressives et temporaires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8fc2fc2 e-flex e-con-boxed e-con e-parent\" data-id=\"8fc2fc2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8c92578 e-con-full e-flex e-con e-child\" data-id=\"8c92578\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c180098 elementor-widget elementor-widget-image\" data-id=\"c180098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-7279\" alt=\"photo botox et acide hyaluronique\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-768x512.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-300x200.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-1024x683.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-1536x1024.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-2048x1366.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-botox-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc73090 e-con-full e-flex e-con e-child\" data-id=\"cc73090\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c75260 elementor-widget elementor-widget-heading\" data-id=\"0c75260\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Injection de toxine botulique pour l'occidentalisation de l\u2019\u0153il asiatique <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcde593 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fcde593\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7319b56 elementor-widget elementor-widget-text-editor\" data-id=\"7319b56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>La toxine botulique* permet de d\u00e9tendre certains muscles autour de l\u2019\u0153il, ce qui red\u00e9finit la forme des paupi\u00e8res et ouvre le regard en douceur. La toxine botulique* est utilis\u00e9e pour relever la queue du sourcil ou le sourcil dans sa globalit\u00e9, pour un regard plus ouvert et structur\u00e9.<\/p><p>(*) La toxine botulique est indiqu\u00e9e pour l\u2019am\u00e9lioration temporaire de l\u2019apparence des rides verticales mod\u00e9r\u00e9es \u00e0 s\u00e9v\u00e8res entre les sourcils, visibles lorsque l\u2019on fronce les sourcils au maximum (rides du lion) et\/ou des rides lat\u00e9rales mod\u00e9r\u00e9es \u00e0 s\u00e9v\u00e8res (pattes d\u2019oie) visibles lors d\u2019un sourire maximal\u00a0 lorsqu\u2019elles provoquent une d\u00e9tresse psychologique importante chez les patients adultes.<br \/>Le lifting du sourcil et l&#8217;occidentalisation de l&#8217;\u0153il asiatique ne sont pas une indication de la toxine botulique, mais le traitement des rides de la patte d\u2019oie et du lion cr\u00e9e un effet de lifting du sourcil et d&#8217;occidentalisation de l&#8217;\u0153il.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c86f00 e-flex e-con-boxed e-con e-parent\" data-id=\"4c86f00\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2025aea e-con-full e-flex e-con e-child\" data-id=\"2025aea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bc4e6c elementor-widget elementor-widget-image\" data-id=\"0bc4e6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"466\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-768x466.webp\" class=\"attachment-medium_large size-medium_large wp-image-7954\" alt=\"photo botx nez\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-768x466.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-300x182.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-1024x622.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-1536x933.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-2048x1243.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/botox-rhinoplastie-medicale-18x12.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e37e419 e-con-full e-flex e-con e-child\" data-id=\"e37e419\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-390987a elementor-widget elementor-widget-heading\" data-id=\"390987a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acide hyaluronique pour l'occidentalisation de l\u2019\u0153il asiatique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-933bd29 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"933bd29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-852dd45 elementor-widget elementor-widget-text-editor\" data-id=\"852dd45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Utilis\u00e9 pour combler ou modifier certaines zones de l\u2019\u0153il, l\u2019acide hyaluronique permet de red\u00e9finir le contour des paupi\u00e8res sup\u00e9rieures. <br \/>Il peut \u00e9galement \u00eatre inject\u00e9 au niveau de l\u2019arcade sourcili\u00e8re pour ajouter un l\u00e9ger volume et donner de la profondeur au regard.<br \/>Ce produit permet \u00e9galement de traiter le vieillissement de l\u2019\u0153il asiatique. Avec le temps la paupi\u00e8re sup\u00e9rieure asiatique se creuse (\u0153il creux), comme toute paupi\u00e8re. La perte de pl\u00e9nitude est trait\u00e9e par injection d&#8217;acide hyaluronique. \u00c0 l&#8217;aide d&#8217;une canule, l&#8217;acide hyaluronique est inject\u00e9 au niveau du rebord orbitaire pour remplacer la graisse qui a fondu.<br \/>Le r\u00e9sultat est imm\u00e9diat et dure environ deux ans. Les suites sont l\u00e9g\u00e8res, marqu\u00e9es par des h\u00e9matomes (rares) et un \u0153d\u00e8me local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de079f5 e-flex e-con-boxed e-con e-parent\" data-id=\"de079f5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-239dc04 e-con-full e-flex e-con e-child\" data-id=\"239dc04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9787a2 elementor-widget elementor-widget-image\" data-id=\"e9787a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"430\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-768x430.webp\" class=\"attachment-medium_large size-medium_large wp-image-9815\" alt=\"photo amplification du point G\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-768x430.webp 768w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-300x168.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-1024x574.webp 1024w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-1536x861.webp 1536w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-2048x1148.webp 2048w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/06\/acide-hyaluronique-point-g-18x10.webp 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fa289e e-con-full e-flex e-con e-child\" data-id=\"3fa289e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd18acd elementor-widget elementor-widget-heading\" data-id=\"bd18acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages des techniques m\u00e9dicales pour l\u2019occidentalisation du regard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcbb80b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dcbb80b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca9b9f5 elementor-widget elementor-widget-text-editor\" data-id=\"ca9b9f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"et_pb_row et_pb_row_4 et_pb_gutters2\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_7 et_pb_css_mix_blend_mode_passthrough et-last-child\"><div class=\"et_pb_module et_pb_text et_pb_text_7 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><div class=\"et_pb_column et_pb_column_1_2 et_pb_column_13 et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_text et_pb_text_15 et_pb_text_align_left et_pb_bg_layout_light\"><div class=\"et_pb_text_inner\"><p>les techniques m\u00e9dicales offrent plusieurs avantages :<br \/>\u2022 R\u00e9sultats naturels : ces traitements permettent d\u2019obtenir un r\u00e9sultat subtil et modulable, respectant la morphologie et les proportions du visage.<br \/>\u2022 Proc\u00e9dures non invasives : ces techniques sont moins invasives que les interventions chirurgicales et elles ne causent pas d\u2019\u00e9viction sociale. <br \/>\u2022 Personnalisation : chaque traitement est adapt\u00e9 au patient pour atteindre les objectifs souhait\u00e9s, tout en conservant l\u2019harmonie naturelle du visage.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80b171a e-flex e-con-boxed e-con e-parent\" data-id=\"80b171a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-179df1e elementor-widget elementor-widget-heading\" data-id=\"179df1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix de l'occidentalisation de l'\u0153il asiatique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30b77b4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"30b77b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8b83c elementor-widget elementor-widget-text-editor\" data-id=\"3d8b83c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 Gen\u00e8ve, les actes m\u00e9dicaux visant \u00e0 occidentaliser le regard asiatique peuvent inclure l\u2019utilisation cibl\u00e9e de toxine botulique ou d\u2019acide hyaluronique, selon les objectifs esth\u00e9tiques d\u00e9finis en consultation. Le tarif des injections d\u2019acide hyaluronique est de 650 CHF par seringue. Les prix des injections de toxine botulique varient en fonction du nombre de zones trait\u00e9es et du sexe du patient.<\/p><p><span style=\"text-decoration: underline;\">Pour les femmes<\/span><\/p><ul><li>Une zone : 300 CHF<\/li><li>Deux zones : 450 CHF<\/li><li>Trois zones : 600 CHF<\/li><\/ul><p><span style=\"text-decoration: underline;\">Pour les hommes<\/span><\/p><ul><li>Une zone : 350 CHF<\/li><li>Deux zones : 500 CHF<\/li><li>Trois zones : 650 CHF<\/li><\/ul><p>Le plan de traitement est \u00e9tabli sur mesure, selon la morphologie de la zone orbitaire, la tonicit\u00e9 des muscles p\u00e9rioculaires et les attentes du patient.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1df77fc e-flex e-con-boxed e-con e-parent\" data-id=\"1df77fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03038fe elementor-widget elementor-widget-heading\" data-id=\"03038fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rences m\u00e9dicales sur l'occidentalisation de l'\u0153il asiatique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4711413 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4711413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a39bc04 elementor-widget elementor-widget-text-editor\" data-id=\"a39bc04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-section-id=\"1608vh6\" data-start=\"780\" data-end=\"1043\">Les diff\u00e9rences morphologiques du regard sont li\u00e9es \u00e0 des variations anatomiques naturelles, notamment au niveau du pli palp\u00e9bral sup\u00e9rieur et des structures p\u00e9ri-orbitaires, largement d\u00e9crites dans les travaux publi\u00e9s par <a href=\"https:\/\/link.springer.com\/journal\/266\"><strong data-start=\"1005\" data-end=\"1042\">Aesthetic Plastic Surgery Journal<\/strong><\/a>.<\/li><li data-section-id=\"52405s\" data-start=\"1045\" data-end=\"1326\">L\u2019analyse esth\u00e9tique du visage n\u00e9cessite une compr\u00e9hension pr\u00e9cise des particularit\u00e9s anatomiques individuelles afin d\u2019adapter chaque traitement sans standardiser les r\u00e9sultats, une approche d\u00e9velopp\u00e9e dans les publications de<a href=\"https:\/\/www.facialplastic.theclinics.com\/\"> <strong data-start=\"1274\" data-end=\"1325\">Facial Plastic Surgery Clinics of North America<\/strong><\/a>.<\/li><li data-section-id=\"19xgf6b\" data-start=\"1328\" data-end=\"1584\">Les traitements m\u00e9dicaux non chirurgicaux de la r\u00e9gion p\u00e9ri-orbitaire reposent sur une connaissance approfondie des tissus, des volumes et des proportions du visage, des \u00e9l\u00e9ments \u00e9tudi\u00e9s dans la litt\u00e9rature scientifique disponible via <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/\"><strong data-start=\"1565\" data-end=\"1583\">PubMed Central<\/strong><\/a>.<\/li><li data-section-id=\"svvc9e\" data-start=\"1586\" data-end=\"1846\">La m\u00e9decine esth\u00e9tique moderne prend en compte la diversit\u00e9 des morphologies faciales et l\u2019importance de pr\u00e9server les caract\u00e9ristiques propres \u00e0 chaque patient, un sujet abord\u00e9 dans les recherches publi\u00e9es par <a href=\"https:\/\/journals.lww.com\/plasreconsurg\/\"><strong data-start=\"1799\" data-end=\"1845\">Plastic and Reconstructive Surgery Journal<\/strong><\/a>.<\/li><li data-section-id=\"9cz5aj\" data-start=\"1848\" data-end=\"2039\">Les actes esth\u00e9tiques utilisant des produits injectables doivent respecter des exigences strictes de qualit\u00e9 et de s\u00e9curit\u00e9, conform\u00e9ment aux standards \u00e9tablis en Suisse par <a href=\"https:\/\/www.swissmedic.ch\/\"><strong data-start=\"2024\" data-end=\"2038\">Swissmedic<\/strong><\/a>.<\/li><li data-section-id=\"iygqzh\" data-start=\"2041\" data-end=\"2243\">Les \u00e9changes scientifiques internationaux autour des proc\u00e9dures esth\u00e9tiques du visage sont soutenus par des organisations sp\u00e9cialis\u00e9es comme <a href=\"https:\/\/www.isaps.org\/\"><strong data-start=\"2184\" data-end=\"2242\">The International Society of Aesthetic Plastic Surgery<\/strong><\/a>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-126f58e e-flex e-con-boxed e-con e-parent\" data-id=\"126f58e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0c814e elementor-widget elementor-widget-heading\" data-id=\"a0c814e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes sur l'occidentalisation de l'\u0153il asiatique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7ca37c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d7ca37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384ecdc elementor-widget elementor-widget-n-accordion\" data-id=\"384ecdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5900\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-5900\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment l\u2019acide hyaluronique est-il utilis\u00e9 pour rehausser le pli palp\u00e9bral sup\u00e9rieur ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5900\" class=\"elementor-element elementor-element-6ff2788 e-con-full e-flex e-con e-child\" data-id=\"6ff2788\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-618c1e6 elementor-widget elementor-widget-text-editor\" data-id=\"618c1e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019acide hyaluronique est inject\u00e9 avec pr\u00e9cision dans la paupi\u00e8re sup\u00e9rieure pour cr\u00e9er ou accentuer le pli palp\u00e9bral. Il redonne du volume, ouvre le regard et imite l\u2019effet d\u2019une double paupi\u00e8re, sans chirurgie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5901\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5901\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Quels sont les avantages des m\u00e9thodes non invasives par rapport \u00e0 la chirurgie pour l\u2019occidentalisation du regard ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5901\" class=\"elementor-element elementor-element-3414aa7 e-con-full e-flex e-con e-child\" data-id=\"3414aa7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7136b elementor-widget elementor-widget-text-editor\" data-id=\"0d7136b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les techniques non chirurgicales sont sans cicatrice, r\u00e9versibles, avec une r\u00e9cup\u00e9ration rapide. Elles offrent un r\u00e9sultat naturel, progressif et personnalis\u00e9, sans les risques li\u00e9s \u00e0 une op\u00e9ration.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5902\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5902\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Les proc\u00e9dures non chirurgicales pour l\u2019occidentalisation de l\u2019\u0153il asiatique sont-elles douloureuses ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5902\" class=\"elementor-element elementor-element-1555585 e-con-full e-flex e-con e-child\" data-id=\"1555585\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a7b460 elementor-widget elementor-widget-text-editor\" data-id=\"1a7b460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Non, ces techniques sont peu douloureuses. Une cr\u00e8me anesth\u00e9siante est appliqu\u00e9e avant les injections, assurant un confort optimal durant la s\u00e9ance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Comment l\\u2019acide hyaluronique est-il utilis\\u00e9 pour rehausser le pli palp\\u00e9bral sup\\u00e9rieur ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"L\\u2019acide hyaluronique est inject\\u00e9 avec pr\\u00e9cision dans la paupi\\u00e8re sup\\u00e9rieure pour cr\\u00e9er ou accentuer le pli palp\\u00e9bral. Il redonne du volume, ouvre le regard et imite l\\u2019effet d\\u2019une double paupi\\u00e8re, sans chirurgie.\"}},{\"@type\":\"Question\",\"name\":\"Quels sont les avantages des m\\u00e9thodes non invasives par rapport \\u00e0 la chirurgie pour l\\u2019occidentalisation du regard ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Les techniques non chirurgicales sont sans cicatrice, r\\u00e9versibles, avec une r\\u00e9cup\\u00e9ration rapide. Elles offrent un r\\u00e9sultat naturel, progressif et personnalis\\u00e9, sans les risques li\\u00e9s \\u00e0 une op\\u00e9ration.\"}},{\"@type\":\"Question\",\"name\":\"Les proc\\u00e9dures non chirurgicales pour l\\u2019occidentalisation de l\\u2019\\u0153il asiatique sont-elles douloureuses ?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Non, ces techniques sont peu douloureuses. Une cr\\u00e8me anesth\\u00e9siante est appliqu\\u00e9e avant les injections, assurant un confort optimal durant la s\\u00e9ance.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d0b65dd e-con-full e-flex e-con e-parent\" data-id=\"d0b65dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cca6d96 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cca6d96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d639ad9 elementor-widget elementor-widget-heading\" data-id=\"d639ad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Autres Zones \u00c0  Traiter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c6b5a8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5c6b5a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6ef549 e-con-full e-flex e-con e-child\" data-id=\"c6ef549\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5bc0f58 e-flex e-con-boxed e-con e-child\" data-id=\"5bc0f58\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5687c elementor-widget elementor-widget-heading\" data-id=\"7b5687c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/regard\/oeil-creux\/\">\u0152il creux<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bb76ab e-flex e-con-boxed e-con e-child\" data-id=\"7bb76ab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c94f659 elementor-widget elementor-widget-heading\" data-id=\"c94f659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/regard\/lifting-sourcil\/\">Lifting sourcil<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a796202 e-flex e-con-boxed e-con e-child\" data-id=\"a796202\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea9db70 elementor-widget elementor-widget-heading\" data-id=\"ea9db70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/regard\/vallee-des-larmes\/\">Vall\u00e9e des larmes<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cb9138 e-con-full e-flex e-con e-child\" data-id=\"8cb9138\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27713c8 elementor-widget elementor-widget-heading\" data-id=\"27713c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/regard\/paupieres-fripees-rides-yeux\/\">Paupi\u00e8res frip\u00e9es<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0326ef5 e-con-full e-flex e-con e-child\" data-id=\"0326ef5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-646adc8 elementor-widget elementor-widget-heading\" data-id=\"646adc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/drromanovaleria.ch\/besoins\/regard\/cernes\/\">Cernes<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3c3f7c e-flex e-con-boxed e-con e-parent\" data-id=\"e3c3f7c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b5a63 elementor-widget elementor-widget-html\" data-id=\"a7b5a63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n.faq-section {\n  font-family: 'Josefin Sans', Georgia, serif;\n  width: 100%;\n  color: #2c2c2c;\n}\n\n.faq-section .form-title {\n  font-size: 0.75em;\n  font-weight: 700;\n  letter-spacing: 0.15em;\n  text-transform: uppercase;\n  margin-bottom: 20px;\n}\n\n.faq-section textarea {\n  width: 100%;\n  border: 1px solid #ddd;\n  padding: 14px 16px;\n  font-size: 0.9em;\n  min-height: 120px;\n  resize: vertical;\n}\n\n.faq-section .btn-send {\n  margin-top: 14px;\n  padding: 11px 28px;\n  background: #c1a25d;\n  color: #fff;\n  font-size: 0.72em;\n  font-weight: 700;\n  text-transform: uppercase;\n  border: none;\n  cursor: pointer;\n}\n\n.faq-section .form-success {\n  display: none;\n  margin-top: 14px;\n  padding: 12px 16px;\n  background: #f8f4ec;\n  border-left: 3px solid #c1a25d;\n}\n\n.faq-list {\n  list-style: none;\n  padding: 0;\n  margin-top: 40px;\n  display: flex;\n  flex-direction: column;\n  gap: 16px;\n}\n\n.faq-item {\n  display: flex;\n  gap: 16px;\n  padding: 18px;\n  background: #fff;\n  border: 1px solid #efefef;\n}\n\n.faq-item.is-answer {\n  margin-left: 40px;\n  background: #fafafa;\n  border-left: 3px solid #c1a25d;\n}\n\n.faq-avatar {\n  width: 40px;\n  height: 40px;\n  border-radius: 50%;\n  background: #e0e0e0;\n  flex-shrink: 0;\n  overflow: hidden;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n.faq-avatar svg {\n  width: 22px;\n  height: 22px;\n  fill: #bbb;\n}\n\n.faq-avatar img {\n  width: 100%;\n  height: 100%;\n  object-fit: cover;\n}\n\n.faq-body {\n  flex: 1;\n}\n\n.faq-author-name {\n  font-size: 0.75em;\n  font-weight: 700;\n  text-transform: uppercase;\n  margin-bottom: 4px;\n}\n\n.faq-text {\n  font-size: 0.87em;\n  line-height: 1.6;\n  color: #555;\n}\n<\/style>\n\n<div class=\"faq-section\">\n\n<p class=\"form-title\">Posez une question sur ce sujet<\/p>\n\n<textarea id=\"faq-question\" placeholder=\"Votre question\u2026\"><\/textarea>\n<button class=\"btn-send\" onclick=\"submitFakeForm()\">Envoyer<\/button>\n\n<div class=\"form-success\" id=\"faq-success\">\nVotre question a bien \u00e9t\u00e9 transmise. Nous vous r\u00e9pondrons rapidement.\n<\/div>\n\n<ul class=\"faq-list\">\n\n<!-- QUESTION -->\n<li class=\"faq-item\">\n  <div class=\"faq-avatar\">\n    <svg viewBox=\"0 0 24 24\"><path d=\"M12 12c2.7 0 4.8-2.1 4.8-4.8S14.7 2.4 12 2.4 7.2 4.5 7.2 7.2 9.3 12 12 12zm0 2.4c-3.2 0-9.6 1.6-9.6 4.8v2.4h19.2v-2.4c0-3.2-6.4-4.8-9.6-4.8z\"\/><\/svg>\n  <\/div>\n  <div class=\"faq-body\">\n    <p class=\"faq-text\">L\u2019occidentalisation de l\u2019\u0153il asiatique sans chirurgie est-elle d\u00e9finitive ?<\/p>\n  <\/div>\n<\/li>\n\n<!-- R\u00c9PONSE -->\n<li class=\"faq-item is-answer\">\n  <div class=\"faq-avatar\">\n    <img decoding=\"async\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/01\/photo-dr.jpg\"\n    onerror=\"this.style.display='none'; this.parentElement.innerHTML='<svg viewBox=\\'0 0 24 24\\'><path d=\\'M12 12c2.7 0 4.8-2.1 4.8-4.8S14.7 2.4 12 2.4 7.2 4.5 7.2 7.2 9.3 12 12 12zm0 2.4c-3.2 0-9.6 1.6-9.6 4.8v2.4h19.2v-2.4c0-3.2-6.4-4.8-9.6-4.8z\\'\/><\/svg>'\"\n    alt=\"Dr. Romanova Valeria\">\n  <\/div>\n  <div class=\"faq-body\">\n    <p class=\"faq-author-name\">Dr. Romanova Valeria<\/p>\n    <p class=\"faq-text\">Non, les r\u00e9sultats sont temporaires. L\u2019acide hyaluronique dure g\u00e9n\u00e9ralement entre 12 et 24 mois, tandis que la toxine botulique agit environ 4 \u00e0 6 mois.<\/p>\n  <\/div>\n<\/li>\n\n<!-- QUESTION -->\n<li class=\"faq-item\">\n  <div class=\"faq-avatar\">\n    <svg viewBox=\"0 0 24 24\"><path d=\"M12 12c2.7 0 4.8-2.1 4.8-4.8S14.7 2.4 12 2.4 7.2 4.5 7.2 7.2 9.3 12 12 12zm0 2.4c-3.2 0-9.6 1.6-9.6 4.8v2.4h19.2v-2.4c0-3.2-6.4-4.8-9.6-4.8z\"\/><\/svg>\n  <\/div>\n  <div class=\"faq-body\">\n    <p class=\"faq-text\">Peut-on cr\u00e9er un pli palp\u00e9bral sans chirurgie ?<\/p>\n  <\/div>\n<\/li>\n\n<!-- R\u00c9PONSE -->\n<li class=\"faq-item is-answer\">\n  <div class=\"faq-avatar\">\n    <img decoding=\"async\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/01\/photo-dr.jpg\"\n    onerror=\"this.style.display='none'; this.parentElement.innerHTML='<svg viewBox=\\'0 0 24 24\\'><path d=\\'M12 12c2.7 0 4.8-2.1 4.8-4.8S14.7 2.4 12 2.4 7.2 4.5 7.2 7.2 9.3 12 12 12zm0 2.4c-3.2 0-9.6 1.6-9.6 4.8v2.4h19.2v-2.4c0-3.2-6.4-4.8-9.6-4.8z\\'\/><\/svg>'\"\n    alt=\"Dr. Romanova Valeria\">\n  <\/div>\n  <div class=\"faq-body\">\n    <p class=\"faq-author-name\">Dr. Romanova Valeria<\/p>\n    <p class=\"faq-text\">Oui, dans certains cas. L\u2019acide hyaluronique permet de cr\u00e9er ou accentuer un pli palp\u00e9bral de mani\u00e8re naturelle.<\/p>\n  <\/div>\n<\/li>\n\n<\/ul>\n<\/div>\n\n<script>\nfunction submitFakeForm() {\n  const q = document.getElementById('faq-question');\n  const success = document.getElementById('faq-success');\n  if (q.value.trim() === '') return;\n  q.value = '';\n  success.style.display = 'block';\n}\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OCCIDENTALISATION DE L&#8217; \u0152IL ASIATIQUE SANS CHIRURGIE Qu&#8217;est-ce que l\u2019Occidentalisation de l\u2019\u0153il asiatique ? L\u2019occidentalisation de l\u2019\u0153il consiste principalement \u00e0 modifier subtilement les contours et les proportions de la paupi\u00e8re et du pli de l\u2019\u0153il, afin de cr\u00e9er un regard plus ouvert et d\u2019ajouter de la profondeur au regard. La demande donc, n&#8217;est pas d&#8217;avoir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":19463,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-19478","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traiter l&#039;oeil asiatique \u00e0 Gen\u00e8ve - Dr Romano<\/title>\n<meta name=\"description\" content=\"Occidentalisez subtilement votre regard \u00e0 Gen\u00e8ve avec des techniques m\u00e9dicales adapt\u00e9es aux yeux asiatiques : ouverture du regard, double paupi\u00e8re, et harmonie naturelle. Les traitements sont laser, toxine botulique et injections d&#039;acide hyaluronique\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drromanovaleria.ch\/en\/asian-beauty\/asian-eyes\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traiter l&#039;oeil asiatique \u00e0 Gen\u00e8ve - Dr Romano\" \/>\n<meta property=\"og:description\" content=\"Occidentalisez subtilement votre regard \u00e0 Gen\u00e8ve avec des techniques m\u00e9dicales adapt\u00e9es aux yeux asiatiques : ouverture du regard, double paupi\u00e8re, et harmonie naturelle. Les traitements sont laser, toxine botulique et injections d&#039;acide hyaluronique\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drromanovaleria.ch\/en\/asian-beauty\/asian-eyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Romano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T07:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/\",\"name\":\"Traiter l'oeil asiatique \u00e0 Gen\u00e8ve - Dr Romano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sculptra-prevention-viellissement-768x512.webp\",\"datePublished\":\"2024-11-17T05:56:49+00:00\",\"dateModified\":\"2026-06-25T07:38:11+00:00\",\"description\":\"Occidentalisez subtilement votre regard \u00e0 Gen\u00e8ve avec des techniques m\u00e9dicales adapt\u00e9es aux yeux asiatiques : ouverture du regard, double paupi\u00e8re, et harmonie naturelle. Les traitements sont laser, toxine botulique et injections d'acide hyaluronique\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sculptra-prevention-viellissement-768x512.webp\",\"contentUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/sculptra-prevention-viellissement-768x512.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/yeux-brides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asiatiques\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/beaute-asiatique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0152il asiatique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/\",\"name\":\"Dr Romano\",\"description\":\"M\u00e9decine morphologique et anti-\u00e2ge\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drromanovaleria.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Treating the Asian Eye in Geneva - Dr. Romano","description":"Subtly westernize your gaze in Geneva with medical techniques tailored to Asian eyes: eye-opening, double eyelid creation, and natural harmony. Treatments include laser, Botulinum toxin, and hyaluronic acid injections.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drromanovaleria.ch\/en\/asian-beauty\/asian-eyes\/","og_locale":"en_GB","og_type":"article","og_title":"Traiter l'oeil asiatique \u00e0 Gen\u00e8ve - Dr Romano","og_description":"Occidentalisez subtilement votre regard \u00e0 Gen\u00e8ve avec des techniques m\u00e9dicales adapt\u00e9es aux yeux asiatiques : ouverture du regard, double paupi\u00e8re, et harmonie naturelle. Les traitements sont laser, toxine botulique et injections d'acide hyaluronique","og_url":"https:\/\/drromanovaleria.ch\/en\/asian-beauty\/asian-eyes\/","og_site_name":"Dr Romano","article_modified_time":"2026-06-25T07:38:11+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/","url":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/","name":"Treating the Asian Eye in Geneva - Dr. Romano","isPartOf":{"@id":"https:\/\/drromanovaleria.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/#primaryimage"},"image":{"@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/#primaryimage"},"thumbnailUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp","datePublished":"2024-11-17T05:56:49+00:00","dateModified":"2026-06-25T07:38:11+00:00","description":"Subtly westernize your gaze in Geneva with medical techniques tailored to Asian eyes: eye-opening, double eyelid creation, and natural harmony. Treatments include laser, Botulinum toxin, and hyaluronic acid injections.","breadcrumb":{"@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/#primaryimage","url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp","contentUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/08\/sculptra-prevention-viellissement-768x512.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/yeux-brides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/drromanovaleria.ch\/"},{"@type":"ListItem","position":2,"name":"Asiatiques","item":"https:\/\/drromanovaleria.ch\/beaute-asiatique\/"},{"@type":"ListItem","position":3,"name":"\u0152il asiatique"}]},{"@type":"WebSite","@id":"https:\/\/drromanovaleria.ch\/#website","url":"https:\/\/drromanovaleria.ch\/","name":"Dr Romano","description":"Morphological and anti-ageing medicine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drromanovaleria.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/19478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/comments?post=19478"}],"version-history":[{"count":5,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/19478\/revisions"}],"predecessor-version":[{"id":71131,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/19478\/revisions\/71131"}],"up":[{"embeddable":true,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/pages\/19463"}],"wp:attachment":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/media?parent=19478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}