{"id":25991,"date":"2025-05-08T13:11:28","date_gmt":"2025-05-08T11:11:28","guid":{"rendered":"https:\/\/drromanovaleria.ch\/?post_type=infographie&#038;p=25991"},"modified":"2026-07-08T16:05:16","modified_gmt":"2026-07-08T14:05:16","slug":"wrinkles-smoking","status":"publish","type":"infographie","link":"https:\/\/drromanovaleria.ch\/en\/infographie\/rides-tabac\/","title":{"rendered":"Comment le tabagisme influence-t-il l\u2019apparition des rides ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25991\" class=\"elementor elementor-25991\" data-elementor-post-type=\"infographie\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15b761a e-flex e-con-boxed e-con e-parent\" data-id=\"15b761a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b1a897 e-con-full e-flex e-con e-child\" data-id=\"5b1a897\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-862acb9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"862acb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">COMMENT LE TABAGISME INFLUENCE-T-IL L'APPARITION DES RIDES ?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df5518 elementor-align-center elementor-widget elementor-widget-breadcrumbs\" data-id=\"1df5518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/drromanovaleria.ch\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b809046 e-flex e-con-boxed e-con e-parent\" data-id=\"b809046\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e19e079 e-flex e-con-boxed e-con e-child\" data-id=\"e19e079\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b64469d e-con-full e-flex e-con e-child\" data-id=\"b64469d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-035f716 elementor-widget elementor-widget-text-editor\" data-id=\"035f716\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le vieillissement cutan\u00e9 est un processus in\u00e9vitable, influenc\u00e9 par des facteurs g\u00e9n\u00e9tiques, hormonaux, environnementaux et comportementaux. Parmi ces derniers, le tabagisme actif ou passif occupe une place centrale. Ses effets d\u00e9l\u00e9t\u00e8res sur la sant\u00e9 cardiovasculaire, respiratoire et oncologique sont bien document\u00e9s, mais son impact sur la peau \u2014 et plus sp\u00e9cifiquement sur l\u2019apparition des rides \u2014 m\u00e9rite une attention tout aussi rigoureuse.<br \/>Le visage d\u2019un(e) fumeur(se) pr\u00e9sente des signes caract\u00e9ristiques : rides pr\u00e9coces, teint terne, rel\u00e2chement marqu\u00e9, et qualit\u00e9 cutan\u00e9e alt\u00e9r\u00e9e. Le tabac, par des m\u00e9canismes multiples, acc\u00e9l\u00e8re le vieillissement cutan\u00e9 et compromet l\u2019efficacit\u00e9 de nombreux traitements esth\u00e9tiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4011be8 e-flex e-con-boxed e-con e-child\" data-id=\"4011be8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-140582a elementor-widget elementor-widget-image\" data-id=\"140582a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"220\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp\" class=\"attachment-medium size-medium wp-image-4852\" alt=\"image peau jeune hydrat\u00e9e\" srcset=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp 300w, https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau-16x12.webp 16w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81c40da elementor-align-center elementor-widget elementor-widget-button\" data-id=\"81c40da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/drromanovaleria.ch\/contactez-le-dr-romano\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prendre rendez-vous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2381c20 e-flex e-con-boxed e-con e-parent\" data-id=\"2381c20\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-053f090 elementor-toc--content-ellipsis elementor-toc--minimized-on-desktop elementor-widget elementor-widget-table-of-contents\" data-id=\"053f090\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;minimized_on&quot;:&quot;desktop&quot;,&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h2 class=\"elementor-toc__header-title\">\n\t\t\t\tSommaire\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__053f090\" aria-expanded=\"true\" aria-label=\"Ouvrir la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__053f090\" aria-expanded=\"true\" aria-label=\"Fermer la table des mati\u00e8res\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__053f090\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05dc116 e-flex e-con-boxed e-con e-parent\" data-id=\"05dc116\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22fd6b2 elementor-widget elementor-widget-text-editor\" data-id=\"22fd6b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Comment le tabac acc\u00e9l\u00e8re-t-il le vieillissement de la peau ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b55c932 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b55c932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f73f2 elementor-widget elementor-widget-text-editor\" data-id=\"07f73f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le tabagisme acc\u00e9l\u00e8re la formation des rides par l\u2019interm\u00e9diaire de plusieurs processus physiopathologiques simultan\u00e9s. Ces effets ne sont pas purement esth\u00e9tiques, en fait ils traduisent une d\u00e9t\u00e9rioration fonctionnelle de la peau.<\/p><ul><li>Diminution de l\u2019oxyg\u00e9nation tissulaire\u00a0: la fum\u00e9e de cigarette contient du monoxyde de carbone, qui se lie \u00e0 l\u2019h\u00e9moglobine avec une affinit\u00e9 bien sup\u00e9rieure \u00e0 celle de l\u2019oxyg\u00e8ne. Il en r\u00e9sulte une hypoxie chronique des tissus, notamment au niveau cutan\u00e9. La peau devient moins bien vascularis\u00e9e, moins bien oxyg\u00e9n\u00e9e, et donc moins capable de se r\u00e9g\u00e9n\u00e9rer.<\/li><li>Diminution de la microcirculation cutan\u00e9e : le tabac induit une vasoconstriction chronique, c\u2019est-\u00e0-dire un r\u00e9tr\u00e9cissement des vaisseaux sanguins. Ce ph\u00e9nom\u00e8ne r\u00e9duit l\u2019apport de nutriments et de facteurs r\u00e9parateurs aux cellules du derme. Cela cause une perte de tonicit\u00e9 cutan\u00e9e, une r\u00e9duction de la synth\u00e8se de collag\u00e8ne, et une capacit\u00e9 de cicatrisation alt\u00e9r\u00e9e.<\/li><li>D\u00e9g\u00e9n\u00e9rescence des fibres de collag\u00e8ne et d\u2019\u00e9lastine\u00a0: la fum\u00e9e de cigarette contient des milliers de substances toxiques, dont certaines (ald\u00e9hydes, hydrocarbures aromatiques) d\u00e9clenchent une production massive de radicaux libres. Ces mol\u00e9cules instables attaquent les prot\u00e9ines de soutien de la peau, notamment le collag\u00e8ne et l\u2019\u00e9lastine, entra\u00eenant un rel\u00e2chement acc\u00e9l\u00e9r\u00e9 et la formation de rides profondes.<\/li><li>Inflammation chronique de bas grade\u00a0: le tabac active des r\u00e9ponses inflammatoires subcliniques qui entretiennent un \u00e9tat de stress oxydatif et fragilisent progressivement les structures dermiques. Cette inflammation de bas grade favorise le vieillissement pr\u00e9matur\u00e9, et accentue la formation de rides, m\u00eame chez les jeunes fumeurs.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b0273f e-flex e-con-boxed e-con e-parent\" data-id=\"0b0273f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-602b7d3 elementor-widget elementor-widget-text-editor\" data-id=\"602b7d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Quelles rides sont caus\u00e9es par le tabagisme ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56e9007 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"56e9007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6df09 elementor-widget elementor-widget-text-editor\" data-id=\"7e6df09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le tabagisme cause un vieillissement tr\u00e8s particulier, dont les signes cliniques sont imm\u00e9diatement identifiables par un \u0153il m\u00e9dical averti. On parle parfois de \u201csmoker\u2019s face\u201d ou \u201cvisage tabagique\u201d, terme utilis\u00e9 dans plusieurs publications m\u00e9dicales.<\/p><ul><li>Rides p\u00e9ribuccales verticales : chez les femmes fumeuses, notamment, on observe souvent des rides verticales autour de la bouche, en haut de la l\u00e8vre sup\u00e9rieure. Celles-ci sont dues \u00e0 la contraction r\u00e9p\u00e9t\u00e9e du muscle orbiculaire lors de l\u2019aspiration de la cigarette, mais aussi \u00e0 une perte de volume dermique induite par l\u2019oxydation.<\/li><li>Rides plus profondes et plus nombreuses\u00a0: des \u00e9tudes ont d\u00e9montr\u00e9 que, \u00e0 \u00e2ge \u00e9gal, les fumeurs pr\u00e9sentent en moyenne plus de rides, et des rides plus profondes, que les non-fumeurs. Cela concerne le front, la patte-d\u2019oie, la glabelle, mais aussi le cou et le d\u00e9collet\u00e9.<\/li><li>Affaissement pr\u00e9matur\u00e9 des tissus : le rel\u00e2chement cutan\u00e9 \u2014 en particulier de l\u2019ovale du visage \u2014 est plus marqu\u00e9 chez les fumeurs, en raison de la perte de densit\u00e9 dermique, de l\u2019alt\u00e9ration de l\u2019organisation du collag\u00e8ne et de la fonte des volumes garisseux.<\/li><li>Teint terne, grain de peau irr\u00e9gulier\u00a0: en compl\u00e9ment des rides, la peau du fumeur perd son \u00e9clat. Elle appara\u00eet gris\u00e2tre, inhomog\u00e8ne, \u00e9paissie ou froiss\u00e9e, ce qui accentue l\u2019effet vieilli du visage, ind\u00e9pendamment des rides elles-m\u00eames.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e1a840 e-flex e-con-boxed e-con e-parent\" data-id=\"2e1a840\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1a2a99 elementor-widget elementor-widget-text-editor\" data-id=\"b1a2a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Comment r\u00e9duire les rides caus\u00e9es par le tabac ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b51dd8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5b51dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-774b133 elementor-widget elementor-widget-text-editor\" data-id=\"774b133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"264\" data-end=\"2492\">Il est possible d\u2019att\u00e9nuer les effets du tabac sur la peau, mais toujours dans une certaine limite. Les rides provoqu\u00e9es par le tabagisme sont en effet plus difficiles \u00e0 traiter une fois qu\u2019elles sont install\u00e9es. Plusieurs approches permettent toutefois de freiner leur \u00e9volution et, dans certains cas, d\u2019en r\u00e9duire la profondeur.<br data-start=\"594\" data-end=\"597\" \/>La premi\u00e8re \u00e9tape incontournable reste l\u2019arr\u00eat du tabac. M\u00eame entrepris tardivement, le sevrage am\u00e9liore la vascularisation cutan\u00e9e, la fermet\u00e9 et la qualit\u00e9 de la peau. Sans ce changement, les traitements esth\u00e9tiques donnent des r\u00e9sultats partiels et moins durables.<br data-start=\"864\" data-end=\"867\" \/>Diff\u00e9rentes techniques peuvent ensuite \u00eatre employ\u00e9es. Les Skinboosters, acide hyaluronique faiblement r\u00e9ticul\u00e9, r\u00e9hydratent le derme et redonnent \u00e0 la\u00a0 peau un aspect plus souple et plus lumineux. <br \/>Les peelings stimulent le renouvellement cellulaire, r\u00e9duisent les rides superficielles et uniformisent le teint. <br \/>Les lasers fractionn\u00e9s, ablatifs ou non, sont particuli\u00e8rement indiqu\u00e9s lorsque les rides sont marqu\u00e9es.<br data-start=\"1303\" data-end=\"1306\" \/>L\u2019acide hyaluronique est utilis\u00e9 pour combler certains sillons, comme les plis d\u2019amertume ou les sillons nasog\u00e9niens. <br \/>Les soins topiques riches en antioxydants \u2014 vitamine C, vitamine E, niacinamide \u2014 et en agents r\u00e9parateurs renforcent ces traitements en luttant contre l\u2019inflammation oxydative et en stimulant les d\u00e9fenses naturelles de la peau.<br data-start=\"1778\" data-end=\"1781\" \/>La m\u00e9soth\u00e9rapie occupe aussi une place int\u00e9ressante, notamment chez les patients jeunes ou en cours de sevrage tabagique. Elle consiste \u00e0 injecter dans le derme un m\u00e9lange d\u2019acides amin\u00e9s, de vitamines, de min\u00e9raux et d\u2019acide hyaluronique non r\u00e9ticul\u00e9 afin de r\u00e9activer les fonctions biologiques locales. Chez les anciens fumeurs, elle stimule la microcirculation, favorise un meilleur renouvellement cellulaire, am\u00e9liore l\u2019oxyg\u00e9nation et la qualit\u00e9 de la peau. R\u00e9alis\u00e9e en cure de deux \u00e0 quatre s\u00e9ances espac\u00e9es de quinze jours, ou en compl\u00e9ment d\u2019autres techniques comme les Skinboosters ou le laser, elle ne comble pas les rides profondes mais redonne de l\u2019\u00e9clat et nourrit efficacement la peau en surface.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4faa51c e-flex e-con-boxed e-con e-parent\" data-id=\"4faa51c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5845d19 elementor-widget elementor-widget-text-editor\" data-id=\"5845d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Le tabagisme passif favorise-t-il les rides ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5063008 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5063008\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd9b8fa elementor-widget elementor-widget-text-editor\" data-id=\"dd9b8fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si le lien entre tabagisme actif et vieillissement cutan\u00e9 est bien \u00e9tabli, celui entre tabagisme passif et d\u00e9gradation de la peau reste encore trop souvent sous-estim\u00e9. Pourtant, l\u2019exposition chronique \u00e0 la fum\u00e9e de cigarette \u2014 sans consommation directe \u2014 peut, elle aussi, alt\u00e9rer significativement la qualit\u00e9 et la structure cutan\u00e9e.<br \/>Le tabagisme passif expose l\u2019organisme \u00e0 de nombreuses substances pr\u00e9sentes dans la fum\u00e9e ambiante : monoxyde de carbone, goudrons, acrol\u00e9ine, benz\u00e8ne, m\u00e9taux lourds. Ces compos\u00e9s toxiques, lorsqu\u2019ils sont inhal\u00e9s de mani\u00e8re r\u00e9p\u00e9t\u00e9e, participent \u00e0 un stress oxydatif syst\u00e9mique. La peau, en tant qu\u2019organe sensible \u00e0 l\u2019environnement et fortement vascularis\u00e9, subit les cons\u00e9quences de cette agression silencieuse.<br \/>Des \u00e9tudes cliniques ont mis en \u00e9vidence que les cohabitants r\u00e9guliers de fumeurs (notamment enfants et conjoints) pr\u00e9sentent un vieillissement cutan\u00e9 acc\u00e9l\u00e9r\u00e9, avec davantage de ridules, un grain de peau alt\u00e9r\u00e9 et un teint moins homog\u00e8ne. Ce ph\u00e9nom\u00e8ne est d\u2019autant plus pr\u00e9occupant qu\u2019il \u00e9chappe souvent \u00e0 la conscience des personnes expos\u00e9es, et qu\u2019il peut commencer d\u00e8s l\u2019enfance.<br \/>Dans le cadre d\u2019une consultation de m\u00e9decine \u00e0 vis\u00e9e esth\u00e9tique, il est donc pertinent de s\u2019int\u00e9resser \u00e0 l\u2019environnement imm\u00e9diat du patient, pas uniquement \u00e0 ses habitudes personnelles. Un traitement anti-\u00e2ge sera d\u2019autant plus efficace qu\u2019il est accompagn\u00e9 de recommandations sur l\u2019hygi\u00e8ne de vie globale, y compris l\u2019\u00e9vitement du tabagisme passif prolong\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7473d2 e-flex e-con-boxed e-con e-parent\" data-id=\"e7473d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e398435 elementor-widget elementor-widget-text-editor\" data-id=\"e398435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Pourquoi le tabac provoque-t-il un vieillissement asym\u00e9trique du visage ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a3aef1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8a3aef1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78d4702 elementor-widget elementor-widget-text-editor\" data-id=\"78d4702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le vieillissement cutan\u00e9 provoqu\u00e9 par le tabac ne se manifeste pas de mani\u00e8re uniforme. De nombreux patients fumeurs pr\u00e9sentent une asym\u00e9trie marqu\u00e9e du visage, qui ne s\u2019explique pas uniquement par des facteurs g\u00e9n\u00e9tiques ou posturaux.<br \/>Cette asym\u00e9trie appara\u00eet sous plusieurs aspects. Du c\u00f4t\u00e9 dominant, celui de la main qui tient la cigarette, les rides sont souvent plus nombreuses et plus profondes, notamment autour des l\u00e8vres, du nez et des yeux. Le sillon nasog\u00e9nien peut aussi se creuser davantage d\u2019un seul c\u00f4t\u00e9, en raison de la r\u00e9p\u00e9tition des mouvements musculaires et d\u2019une vascularisation plus fragile. Chez les conducteurs r\u00e9guliers, le c\u00f4t\u00e9 gauche du visage vieillit souvent plus vite : constamment expos\u00e9 \u00e0 la fen\u00eatre, il subit \u00e0 la fois l\u2019effet des rayons UV et celui de la fum\u00e9e, ce qui acc\u00e9l\u00e8re la d\u00e9gradation du derme.<br data-start=\"1173\" data-end=\"1176\" \/>En consultation, cette asym\u00e9trie fournit de pr\u00e9cieuses indications sur le mode de vie et l\u2019environnement du patient. Elle doit \u00eatre prise en compte dans le diagnostic, orienter les choix th\u00e9rapeutiques et guider les recommandations de photoprotection et d\u2019hygi\u00e8ne posturale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5b8541 e-flex e-con-boxed e-con e-parent\" data-id=\"b5b8541\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12d30ec elementor-widget elementor-widget-text-editor\" data-id=\"12d30ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Pourquoi le tabac rend-il la peau terne et vieillie ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79e069b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"79e069b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4497245 elementor-widget elementor-widget-text-editor\" data-id=\"4497245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le teint terne, gris\u00e2tre ou jauni, est l\u2019une des cons\u00e9quences les plus visibles \u2014 et les plus imm\u00e9diates \u2014 du tabagisme sur la peau. Il r\u00e9sulte de plusieurs m\u00e9canismes intriqu\u00e9s, tous d\u00e9l\u00e9t\u00e8res pour la microcirculation cutan\u00e9e et l\u2019\u00e9clat naturel du visage.<br \/>Tout d\u2019abord, la fum\u00e9e de cigarette diminue la vasodilatation capillaire, en raison d\u2019une vasoconstriction chronique induite par la nicotine. Cela entra\u00eene une r\u00e9duction du flux sanguin en surface, donc un apport amoindri en oxyg\u00e8ne et en nutriments. Le derme s\u2019atrophie progressivement, et l\u2019\u00e9piderme perd son \u00e9clat.<br \/>Ensuite, le tabac induit une accumulation de cellules mortes \u00e0 la surface de la peau. Le renouvellement cellulaire est ralenti, le grain de peau devient plus irr\u00e9gulier, et la lumi\u00e8re est moins bien r\u00e9fl\u00e9chie. C\u2019est ce qui explique l\u2019apparence \u201c\u00e9teinte\u201d ou \u201casphyxi\u00e9e\u201d du teint chez de nombreux fumeurs, m\u00eame jeunes.<br \/>Enfin, le stress oxydatif permanent, associ\u00e9 \u00e0 la production de radicaux libres, favorise une oxydation des lipides cutan\u00e9s et une d\u00e9gradation progressive des chromophores naturels.<br \/>La seule mani\u00e8re durable de restaurer l\u2019\u00e9clat du teint est d\u2019interrompre l\u2019exposition tabagique, puis d\u2019accompagner ce sevrage par des traitements m\u00e9dicaux adapt\u00e9s (peelings doux, peeling laser, Skinboosters\u00a0, m\u00e9soth\u00e9rapie), associ\u00e9s \u00e0 une routine dermocosm\u00e9tique antioxydante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f58aba e-flex e-con-boxed e-con e-parent\" data-id=\"6f58aba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf5610b elementor-widget elementor-widget-text-editor\" data-id=\"cf5610b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Peut-on r\u00e9parer les effets du tabac sur les rides et la peau ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe280d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cbe280d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff9291 elementor-widget elementor-widget-text-editor\" data-id=\"8ff9291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le tabagisme influence profond\u00e9ment l\u2019apparition et l\u2019\u00e9volution des rides. En alt\u00e9rant l\u2019oxyg\u00e9nation des tissus, en d\u00e9sorganisant les fibres de soutien et en causant une inflammation sourde, il acc\u00e9l\u00e8re le vieillissement du visage de mani\u00e8re visible et mesurable. Les rides sont plus nombreuses, plus profondes, plus pr\u00e9coces chez les fumeurs \u2014 hommes comme femmes.<br \/>Le diagnostic de vieillissement li\u00e9 au tabac impose une prise en charge sp\u00e9cifique, associant une strat\u00e9gie th\u00e9rapeutique rigoureuse \u00e0 un accompagnement vers le sevrage. C\u2019est la condition indispensable \u00e0 des r\u00e9sultats durables et harmonieux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-963cdf4 e-flex e-con-boxed e-con e-parent\" data-id=\"963cdf4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-40f68ad e-con-full e-flex e-con e-child\" data-id=\"40f68ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-f8d43a5 e-con-full e-flex e-con e-child\" data-id=\"f8d43a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-628f03b e-con-full e-flex e-con e-child\" data-id=\"628f03b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-9670481 e-con-full e-flex e-con e-child\" data-id=\"9670481\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe209b elementor-widget elementor-widget-image\" data-id=\"7fe209b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/07\/photo-docteur-romano-valeria-150x150.webp\" class=\"attachment-thumbnail size-thumbnail wp-image-13266\" alt=\"Photo docteur Valeria Romano \u00e0 Gen\u00e8ve\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-238c90a elementor-widget elementor-widget-text-editor\" data-id=\"238c90a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Article r\u00e9dig\u00e9 par le <a href=\"https:\/\/drromanovaleria.ch\/\">Dr Romano Valeria<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b7ed18 e-con-full e-flex e-con e-child\" data-id=\"9b7ed18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66c0d5b elementor-widget elementor-widget-text-editor\" data-id=\"66c0d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PARTAGER CET ARTICLE SUR<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7444731 elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"7444731\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-546a1c8 elementor-align-start elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"546a1c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:dr.romano.valeria@gmail.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">dr.romano.valeria@gmail.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41%2078%20209%2002%2089\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+41 78 209 02 89<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":0,"template":"elementor_header_footer","class_list":["post-25991","infographie","type-infographie","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment le tabagisme influence-t-il l&#039;apparition des rides ? - Dr Romano<\/title>\n<meta name=\"description\" content=\"Effets du tabagisme sur la peau : r\u00e9duction du collag\u00e8ne, stress oxydatif, mauvaise oxyg\u00e9nation et acc\u00e9l\u00e9ration du vieillissement cutan\u00e9 avec apparition de rides.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drromanovaleria.ch\/en\/infographic\/wrinkles-smoking\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment le tabagisme influence-t-il l&#039;apparition des rides ? - Dr Romano\" \/>\n<meta property=\"og:description\" content=\"Effets du tabagisme sur la peau : r\u00e9duction du collag\u00e8ne, stress oxydatif, mauvaise oxyg\u00e9nation et acc\u00e9l\u00e9ration du vieillissement cutan\u00e9 avec apparition de rides.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drromanovaleria.ch\/en\/infographic\/wrinkles-smoking\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr Romano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T14:05:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/\",\"name\":\"Comment le tabagisme influence-t-il l'apparition des rides ? - Dr Romano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hydratation-peau.webp\",\"datePublished\":\"2025-05-08T11:11:28+00:00\",\"dateModified\":\"2026-07-08T14:05:16+00:00\",\"description\":\"Effets du tabagisme sur la peau : r\u00e9duction du collag\u00e8ne, stress oxydatif, mauvaise oxyg\u00e9nation et acc\u00e9l\u00e9ration du vieillissement cutan\u00e9 avec apparition de rides.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hydratation-peau.webp\",\"contentUrl\":\"https:\\\/\\\/drromanovaleria.ch\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hydratation-peau.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/rides-tabac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infographie\",\"item\":\"https:\\\/\\\/drromanovaleria.ch\\\/infographie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment le tabagisme influence-t-il l&#8217;apparition des rides ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drromanovaleria.ch\\\/#website\",\"url\":\"https:\\\/\\\/drromanovaleria.ch\\\/\",\"name\":\"Dr Romano\",\"description\":\"M\u00e9decine morphologique et anti-\u00e2ge\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drromanovaleria.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How does smoking influence the appearance of wrinkles ? - Dr Romano","description":"Effects of smoking on the skin : reduced collagen, oxidative stress, poor oxygenation and accelerated skin aging with the appearance of wrinkles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drromanovaleria.ch\/en\/infographic\/wrinkles-smoking\/","og_locale":"en_GB","og_type":"article","og_title":"Comment le tabagisme influence-t-il l'apparition des rides ? - Dr Romano","og_description":"Effets du tabagisme sur la peau : r\u00e9duction du collag\u00e8ne, stress oxydatif, mauvaise oxyg\u00e9nation et acc\u00e9l\u00e9ration du vieillissement cutan\u00e9 avec apparition de rides.","og_url":"https:\/\/drromanovaleria.ch\/en\/infographic\/wrinkles-smoking\/","og_site_name":"Dr Romano","article_modified_time":"2026-07-08T14:05:16+00:00","og_image":[{"width":300,"height":220,"url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/","url":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/","name":"How does smoking influence the appearance of wrinkles ? - Dr Romano","isPartOf":{"@id":"https:\/\/drromanovaleria.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/#primaryimage"},"image":{"@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/#primaryimage"},"thumbnailUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp","datePublished":"2025-05-08T11:11:28+00:00","dateModified":"2026-07-08T14:05:16+00:00","description":"Effects of smoking on the skin : reduced collagen, oxidative stress, poor oxygenation and accelerated skin aging with the appearance of wrinkles.","breadcrumb":{"@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/#primaryimage","url":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp","contentUrl":"https:\/\/drromanovaleria.ch\/wp-content\/uploads\/2024\/05\/hydratation-peau.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/drromanovaleria.ch\/infographie\/rides-tabac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/drromanovaleria.ch\/"},{"@type":"ListItem","position":2,"name":"Infographie","item":"https:\/\/drromanovaleria.ch\/infographie\/"},{"@type":"ListItem","position":3,"name":"Comment le tabagisme influence-t-il l&#8217;apparition des rides ?"}]},{"@type":"WebSite","@id":"https:\/\/drromanovaleria.ch\/#website","url":"https:\/\/drromanovaleria.ch\/","name":"Dr Romano","description":"Morphological and anti-ageing medicine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drromanovaleria.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/infographie\/25991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/infographie"}],"about":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/types\/infographie"}],"version-history":[{"count":5,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/infographie\/25991\/revisions"}],"predecessor-version":[{"id":73520,"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/infographie\/25991\/revisions\/73520"}],"wp:attachment":[{"href":"https:\/\/drromanovaleria.ch\/en\/wp-json\/wp\/v2\/media?parent=25991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}